{"id":129483,"date":"2022-11-14T02:00:18","date_gmt":"2022-11-14T01:00:18","guid":{"rendered":"https:\/\/shop.budrich.de\/produkt\/objektive-hermeneutik\/"},"modified":"2024-04-19T09:46:51","modified_gmt":"2024-04-19T07:46:51","slug":"objektive-hermeneutik","status":"publish","type":"product","link":"https:\/\/shop.budrich.de\/en\/produkt\/objektive-hermeneutik\/","title":{"rendered":"Objektive Hermeneutik"},"content":{"rendered":"<p><b>Die Objektive Hermeneutik ist eine weit verbreitete rekonstruktive Forschungsmethode, die im gesamten Spektrum der Geistes- und Sozialwissenschaften Anwendung findet. Das vorliegende Handbuch f\u00fchrt in grundlegende Begriffe und Verfahren ein, gibt Einblicke in die Analyse spezifischer Datentypen wie Interaktionsprotokolle, Interviews, Briefe, biographisches Material oder Video und veranschaulicht das Vorgehen an konkreten Beispielen. Dadurch bietet das Handbuch Orientierung f\u00fcr Studierende und Forschende, die ein konkretes Datenmaterial mit der Objektiven Hermeneutik untersuchen m\u00f6chten.<\/b><\/p>\n<p>Die Objektive Hermeneutik ist eine in den Sozial- und Kulturwissenschaften verbreitete rekonstruktive Forschungsmethode, die der Interpretation sprachlicher und nichtsprachlicher Ausdrucksgestalten dient. Urspr\u00fcnglich von dem Soziologen Ulrich Oevermann entwickelt, findet diese Methode heute nicht nur in der Soziologie, sondern auch in der P\u00e4dagogik, Sozialen Arbeit, Politikwissenschaft, Geschichte und auf vielen anderen Feldern der Geistes- und Sozialwissenschaften Anwendung und geh\u00f6rt zum Standard der Methodenausbildung.\u00a0Das \u201eHandbuch Objektive Hermeneutik\u201c bietet eine zusammenh\u00e4ngende Gesamtdarstellung der Methode auf allen ihren Anwendungsfeldern. Es enth\u00e4lt Artikel, in denen dargelegt wird, wie das sequenzanalytische Verfahren jeweils f\u00fcr einen spezifischen Datentypus bzw. eine spezifische Ausdrucksmaterialit\u00e4t \u2013 ein Interaktionsprotokoll, Interview, Brief, Bild, Foto, Film etc. \u2013 angewendet werden kann. Grundlegende \u00dcberlegungen zum Forschungsdesign und zur methodologischen Begr\u00fcndung werden in einer vorangestellten Einleitung behandelt. Es folgen Gruppen von Einzelartikeln, in denen die Sequenzanalyse einzelner Materialtypen behandelt und an konkreten Beispielen das Vorgehen veranschaulicht wird. Angesprochen werden in diesem Zusammenhang typische Besonderheiten des Vorgehens sowie Schwierigkeiten bei der Darstellung von Analysen.\u00a0\u00a0Die Einzelartikel orientieren sich am Bed\u00fcrfnis wissenschaftlicher Novizen, die wissen wollen, wie mit der Objektiven Hermeneutik angesichts eines konkreten Datenmaterials gearbeitet werden kann. In der Zusammenschau der Artikel wird der generalistische Ansatz der Objektiven Hermeneutik sichtbar. Der Band unternimmt insofern eine Systematisierung aus vierzig Jahren forschungspraktischer Erfahrung. Das Handbuch wendet sich an Studierende und Absolventen des gesamten Spektrums der Geistes-, Kultur- und Sozialwissenschaften, insbesondere solche der Soziologie, P\u00e4dagogik, Sozialen Arbeit und Geschichte.<\/p>\n<p><strong><a href=\"https:\/\/shop.budrich.de\/wp-content\/uploads\/2022\/04\/9783825259440_inhaltsverzeichnis_leseprobe.pdf\" target=\"_blank\" rel=\"noopener\">Inhaltsverzeichnis + Leseprobe<\/a><\/strong><\/p>\n<p><strong>Die Herausgeber*innen<\/strong>:<br \/>\n<strong>PD Dr. Andreas Franzmann<\/strong>, Institut f\u00fcr P\u00e4dagogische Diagnostik IPD Siegburg<br \/>\n<strong>Dr. Marianne Rychner<\/strong>, Hochschule Luzern und P\u00e4dagogische Hochschulen Nordwestschweiz und Bern<br \/>\n<strong>Prof. Dr. Claudia Scheid<\/strong>, Universit\u00e4t Innsbruck, \u00d6sterreich<br \/>\n<strong>PD Dr. Johannes Twardella<\/strong>, Goethe-Universit\u00e4t Frankfurt am Main<\/p>\n<p>Hier finden Sie den <a href=\"https:\/\/shop.budrich.de\/wp-content\/uploads\/2022\/11\/5944-franzmann.pdf\" target=\"_blank\" rel=\"noopener\">Waschzettel<\/a> zum Buch (PDF-Infoblatt).<\/p>\n<p><strong>Die Zielgruppe:<\/strong><br \/>\nStudierende, Lehrende und Forschende der Erziehungs- und Sozialwissenschaften<\/p>","protected":false},"excerpt":{"rendered":"<p>Die Objektive Hermeneutik ist eine weit verbreitete rekonstruktive Forschungsmethode, die im gesamten Spektrum der Geistes- und Sozialwissenschaften Anwendung findet. Das vorliegende Handbuch f\u00fchrt in grundlegende Begriffe und Verfahren ein, gibt Einblicke in die Analyse spezifischer Datentypen wie Interaktionsprotokolle, Interviews, Briefe, biographisches Material oder Video und veranschaulicht das Vorgehen an konkreten Beispielen. Dadurch bietet das Handbuch [&hellip;]<\/p>\n","protected":false},"featured_media":129276,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[7589,7696,23842,7609,23640],"product_tag":[54259,7698,41388,24209,46780,7732,46781,7687,9271],"class_list":["post-129483","product","type-product","status-publish","has-post-thumbnail","product_author-andreas-franzmann","product_author-marianne-rychner","product_author-claudia-scheid","product_author-twardella-johannes","product_cat-gesellschaft","product_cat-methoden","product_cat-fachbereiche","product_cat-erziehung","product_cat-utb","product_tag-zsm-2024","product_tag-objektive-hermeneutik","product_tag-sequenzanalyse","product_tag-rekonstruktive-methode","product_tag-oevermann","product_tag-qualitative-sozialforschung","product_tag-methodenhandbuch","product_tag-fallanalyse","product_tag-fallrekonstruktion","pa_verlag-utb","wpbf-post","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Objektive Hermeneutik<\/title>\n<meta name=\"description\" content=\"Andreas Franzmann u.a. (Hrsg.): Handbuch zur Methodik in ihren Anwendungsfeldern. utb. ISBN: 978-3-8252-5944-0. Erscheinungstermin: 14.11.2022.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/shop.budrich.de\/en\/product-2\/objektive-hermeneutik\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Objektive Hermeneutik\" \/>\n<meta property=\"og:description\" content=\"Andreas Franzmann u.a. (Hrsg.): Handbuch zur Methodik in ihren Anwendungsfeldern. utb. ISBN: 978-3-8252-5944-0. Erscheinungstermin: 14.11.2022.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/shop.budrich.de\/en\/product-2\/objektive-hermeneutik\/\" \/>\n<meta property=\"og:site_name\" content=\"Verlag Barbara Budrich\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-19T07:46:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/shop.budrich.de\/wp-content\/uploads\/2022\/04\/9783825259440-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1451\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/objektive-hermeneutik\\\/\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/objektive-hermeneutik\\\/\",\"name\":\"Objektive Hermeneutik\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/objektive-hermeneutik\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/objektive-hermeneutik\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/9783825259440-scaled.jpg\",\"datePublished\":\"2022-11-14T01:00:18+00:00\",\"dateModified\":\"2024-04-19T07:46:51+00:00\",\"description\":\"Andreas Franzmann u.a. (Hrsg.): Handbuch zur Methodik in ihren Anwendungsfeldern. utb. ISBN: 978-3-8252-5944-0. Erscheinungstermin: 14.11.2022.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/objektive-hermeneutik\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/objektive-hermeneutik\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/objektive-hermeneutik\\\/#primaryimage\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/9783825259440-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/9783825259440-scaled.jpg\",\"width\":1451,\"height\":2048},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/objektive-hermeneutik\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/shop.budrich.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Programm\",\"item\":\"https:\\\/\\\/shop.budrich.de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Objektive Hermeneutik\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#website\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/\",\"name\":\"Verlag Barbara Budrich\",\"description\":\"Qualitativ hochwertige Publikationen f\u00fcr die Sozial- und Erziehungswissenschaften\",\"publisher\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/shop.budrich.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#organization\",\"name\":\"Verlag Barbara Budrich GmbH\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/verlag-barbara-budrich-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/verlag-barbara-budrich-logo.jpg\",\"width\":354,\"height\":354,\"caption\":\"Verlag Barbara Budrich GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Objektive Hermeneutik","description":"Andreas Franzmann u.a. (Hrsg.): Handbuch zur Methodik in ihren Anwendungsfeldern. utb. ISBN: 978-3-8252-5944-0. Erscheinungstermin: 14.11.2022.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/shop.budrich.de\/en\/product-2\/objektive-hermeneutik\/","og_locale":"en_US","og_type":"article","og_title":"Objektive Hermeneutik","og_description":"Andreas Franzmann u.a. (Hrsg.): Handbuch zur Methodik in ihren Anwendungsfeldern. utb. ISBN: 978-3-8252-5944-0. Erscheinungstermin: 14.11.2022.","og_url":"https:\/\/shop.budrich.de\/en\/product-2\/objektive-hermeneutik\/","og_site_name":"Verlag Barbara Budrich","article_modified_time":"2024-04-19T07:46:51+00:00","og_image":[{"width":1451,"height":2048,"url":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2022\/04\/9783825259440-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/shop.budrich.de\/produkt\/objektive-hermeneutik\/","url":"https:\/\/shop.budrich.de\/produkt\/objektive-hermeneutik\/","name":"Objektive Hermeneutik","isPartOf":{"@id":"https:\/\/shop.budrich.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/shop.budrich.de\/produkt\/objektive-hermeneutik\/#primaryimage"},"image":{"@id":"https:\/\/shop.budrich.de\/produkt\/objektive-hermeneutik\/#primaryimage"},"thumbnailUrl":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2022\/04\/9783825259440-scaled.jpg","datePublished":"2022-11-14T01:00:18+00:00","dateModified":"2024-04-19T07:46:51+00:00","description":"Andreas Franzmann u.a. (Hrsg.): Handbuch zur Methodik in ihren Anwendungsfeldern. utb. ISBN: 978-3-8252-5944-0. Erscheinungstermin: 14.11.2022.","breadcrumb":{"@id":"https:\/\/shop.budrich.de\/produkt\/objektive-hermeneutik\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/shop.budrich.de\/produkt\/objektive-hermeneutik\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/shop.budrich.de\/produkt\/objektive-hermeneutik\/#primaryimage","url":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2022\/04\/9783825259440-scaled.jpg","contentUrl":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2022\/04\/9783825259440-scaled.jpg","width":1451,"height":2048},{"@type":"BreadcrumbList","@id":"https:\/\/shop.budrich.de\/produkt\/objektive-hermeneutik\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/shop.budrich.de\/"},{"@type":"ListItem","position":2,"name":"Programm","item":"https:\/\/shop.budrich.de\/shop\/"},{"@type":"ListItem","position":3,"name":"Objektive Hermeneutik"}]},{"@type":"WebSite","@id":"https:\/\/shop.budrich.de\/#website","url":"https:\/\/shop.budrich.de\/","name":"Verlag Barbara Budrich","description":"Qualitativ hochwertige Publikationen f\u00fcr die Sozial- und Erziehungswissenschaften","publisher":{"@id":"https:\/\/shop.budrich.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/shop.budrich.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/shop.budrich.de\/#organization","name":"Verlag Barbara Budrich GmbH","url":"https:\/\/shop.budrich.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/shop.budrich.de\/#\/schema\/logo\/image\/","url":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2020\/11\/verlag-barbara-budrich-logo.jpg","contentUrl":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2020\/11\/verlag-barbara-budrich-logo.jpg","width":354,"height":354,"caption":"Verlag Barbara Budrich GmbH"},"image":{"@id":"https:\/\/shop.budrich.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product\/129483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/comments?post=129483"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/media\/129276"}],"wp:attachment":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/media?parent=129483"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product_brand?post=129483"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product_cat?post=129483"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product_tag?post=129483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}