{"id":136835,"date":"2023-03-13T02:00:00","date_gmt":"2023-03-13T01:00:00","guid":{"rendered":"https:\/\/shop.budrich.de\/produkt\/kritische-kinderrechtsforschung\/"},"modified":"2026-06-11T14:00:36","modified_gmt":"2026-06-11T12:00:36","slug":"kritische-kinderrechtsforschung","status":"publish","type":"product","link":"https:\/\/shop.budrich.de\/en\/produkt\/kritische-kinderrechtsforschung\/","title":{"rendered":"Kritische Kinderrechtsforschung"},"content":{"rendered":"<p><strong>Das Buch beleuchtet die Debatte und Forschung zu Kinderrechten. Es macht auf Themen aufmerksam, die bisher vernachl\u00e4ssigt wurden, und skizziert neue Konturen und ethische ebenso wie politische Herausforderungen einer kritischen Kinderrechtsforschung, die sich den Kindern als sozialen Subjekten verpflichtet sieht. Es greift hierzu Diskussionen auf, die im Globalen S\u00fcden, insbesondere in Lateinamerika gef\u00fchrt werden.<\/strong><\/p>\n<p>Mit den Kinderrechten werden Kinder als Subjekte anerkannt. Doch ein Rechtssubjekt zu sein, ist mit Ambivalenzen und Paradoxien verbunden. Das Buch beleuchtet einige Defizite und Herausforderungen der Debatte und Forschung zu Kinderrechten. Es macht auf Themen aufmerksam, die bisher vernachl\u00e4ssigt wurden, wie die wirtschaftlichen und Arbeitsrechte sowie das Wahlrecht von Kindern. Dies gilt auch f\u00fcr die Frage, inwieweit Kinderrechte zu mehr Gerechtigkeit beitragen, insbesondere zu sozialer und intergenerationaler Gerechtigkeit. Im Buch werden neue Konturen und ethische ebenso wie politische Herausforderungen einer kritischen Kinderrechtsforschung skizziert, die sich den Kindern als sozialen Subjekten und ihrer Emanzipation aus unn\u00f6tigen Abh\u00e4ngigkeiten verpflichtet sieht. Es greift hierzu Diskussionen auf, die im Globalen S\u00fcden, insbesondere in Lateinamerika gef\u00fchrt werden.<\/p>\n<p><strong><a href=\"https:\/\/shop.budrich.de\/wp-content\/uploads\/2023\/03\/9783847427087_inhaltsverzeichnis_leseprobe.pdf\" target=\"_blank\" rel=\"noopener\">Inhaltsverzeichnis + Leseprobe<\/a><\/strong><\/p>\n<p><strong>Der Autor:<\/strong><br \/>\n<strong>Prof. Dr. Manfred Liebel<\/strong>, unabh\u00e4ngiger Sozialforscher. Ehedem Prof. f\u00fcr Soziologie an der TU Berlin, Honorarprofessor f\u00fcr interkulturelle Kindheits- und Kinderrechtsforschung und Schirmherr des Master \u201eChildhood Studies and Children\u2019s Rights\u201c an der FH Potsdam<\/p>\n<p>Hier finden Sie den <a href=\"https:\/\/shop.budrich.de\/wp-content\/uploads\/2023\/03\/2708-liebel.pdf\" target=\"_blank\" rel=\"noopener\">Waschzettel<\/a> zum Buch (PDF-Infoblatt).<\/p>\n<p><strong>Die Zielgruppe:<\/strong><br \/>\nStudierende, Lehrende und Forschende der Bildungs-, Sozial- und Rechtswissenschaften.<\/p>","protected":false},"excerpt":{"rendered":"<p>Das Buch beleuchtet die Debatte und Forschung zu Kinderrechten. Es macht auf Themen aufmerksam, die bisher vernachl\u00e4ssigt wurden, und skizziert neue Konturen und ethische ebenso wie politische Herausforderungen einer kritischen Kinderrechtsforschung, die sich den Kindern als sozialen Subjekten verpflichtet sieht. Es greift hierzu Diskussionen auf, die im Globalen S\u00fcden, insbesondere in Lateinamerika gef\u00fchrt werden. Mit [&hellip;]<\/p>\n","protected":false},"featured_media":138458,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[52833,23842,7609,7598],"product_tag":[53916,56549,8709,9093,31653,51063,8787,8052,7993,25971,26467,8884],"class_list":["post-136835","product","type-product","status-publish","has-post-thumbnail","product_author-manfred-liebel","product_cat-bestseller","product_cat-fachbereiche","product_cat-erziehung","product_cat-soziale-arbeit","product_tag-dgfe-kongress","product_tag-schwerpunkt-kinderrechte","product_tag-kinderrechte","product_tag-kindheiten","product_tag-subjektivitaet","product_tag-kinderwahlrecht","product_tag-gerechtigkeit","product_tag-resilienz","product_tag-partizipation","product_tag-forschungsethik","product_tag-globaler-sueden","product_tag-lateinamerika","pa_verlag-verlag-barbara-budrich","wpbf-post","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kritische Kinderrechtsforschung<\/title>\n<meta name=\"description\" content=\"Liebel: Politische Subjektivit\u00e4t und die Gegenrechte der Kinder. Verlag Barbara Budrich, ISBN: 78-3-8474-2708-7. Erscheinungstermin: 13.03.2023.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/shop.budrich.de\/en\/product-2\/kritische-kinderrechtsforschung\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kritische Kinderrechtsforschung\" \/>\n<meta property=\"og:description\" content=\"Liebel: Politische Subjektivit\u00e4t und die Gegenrechte der Kinder. Verlag Barbara Budrich, ISBN: 78-3-8474-2708-7. Erscheinungstermin: 13.03.2023.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/shop.budrich.de\/en\/product-2\/kritische-kinderrechtsforschung\/\" \/>\n<meta property=\"og:site_name\" content=\"Verlag Barbara Budrich\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-11T12:00:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/shop.budrich.de\/wp-content\/uploads\/2022\/12\/9783847427087-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1444\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/kritische-kinderrechtsforschung\\\/\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/kritische-kinderrechtsforschung\\\/\",\"name\":\"Kritische Kinderrechtsforschung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/kritische-kinderrechtsforschung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/kritische-kinderrechtsforschung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/9783847427087-1-scaled.jpg\",\"datePublished\":\"2023-03-13T01:00:00+00:00\",\"dateModified\":\"2026-06-11T12:00:36+00:00\",\"description\":\"Liebel: Politische Subjektivit\u00e4t und die Gegenrechte der Kinder. Verlag Barbara Budrich, ISBN: 78-3-8474-2708-7. Erscheinungstermin: 13.03.2023.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/kritische-kinderrechtsforschung\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/kritische-kinderrechtsforschung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/kritische-kinderrechtsforschung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/9783847427087-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/9783847427087-1-scaled.jpg\",\"width\":1444,\"height\":2048},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/kritische-kinderrechtsforschung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/shop.budrich.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Programm\",\"item\":\"https:\\\/\\\/shop.budrich.de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kritische Kinderrechtsforschung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#website\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/\",\"name\":\"Verlag Barbara Budrich\",\"description\":\"Qualitativ hochwertige Publikationen f\u00fcr die Sozial- und Erziehungswissenschaften\",\"publisher\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/shop.budrich.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#organization\",\"name\":\"Verlag Barbara Budrich GmbH\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/verlag-barbara-budrich-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/verlag-barbara-budrich-logo.jpg\",\"width\":354,\"height\":354,\"caption\":\"Verlag Barbara Budrich GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kritische Kinderrechtsforschung","description":"Liebel: Politische Subjektivit\u00e4t und die Gegenrechte der Kinder. Verlag Barbara Budrich, ISBN: 78-3-8474-2708-7. Erscheinungstermin: 13.03.2023.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/shop.budrich.de\/en\/product-2\/kritische-kinderrechtsforschung\/","og_locale":"en_US","og_type":"article","og_title":"Kritische Kinderrechtsforschung","og_description":"Liebel: Politische Subjektivit\u00e4t und die Gegenrechte der Kinder. Verlag Barbara Budrich, ISBN: 78-3-8474-2708-7. Erscheinungstermin: 13.03.2023.","og_url":"https:\/\/shop.budrich.de\/en\/product-2\/kritische-kinderrechtsforschung\/","og_site_name":"Verlag Barbara Budrich","article_modified_time":"2026-06-11T12:00:36+00:00","og_image":[{"width":1444,"height":2048,"url":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2022\/12\/9783847427087-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/shop.budrich.de\/produkt\/kritische-kinderrechtsforschung\/","url":"https:\/\/shop.budrich.de\/produkt\/kritische-kinderrechtsforschung\/","name":"Kritische Kinderrechtsforschung","isPartOf":{"@id":"https:\/\/shop.budrich.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/shop.budrich.de\/produkt\/kritische-kinderrechtsforschung\/#primaryimage"},"image":{"@id":"https:\/\/shop.budrich.de\/produkt\/kritische-kinderrechtsforschung\/#primaryimage"},"thumbnailUrl":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2022\/12\/9783847427087-1-scaled.jpg","datePublished":"2023-03-13T01:00:00+00:00","dateModified":"2026-06-11T12:00:36+00:00","description":"Liebel: Politische Subjektivit\u00e4t und die Gegenrechte der Kinder. Verlag Barbara Budrich, ISBN: 78-3-8474-2708-7. Erscheinungstermin: 13.03.2023.","breadcrumb":{"@id":"https:\/\/shop.budrich.de\/produkt\/kritische-kinderrechtsforschung\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/shop.budrich.de\/produkt\/kritische-kinderrechtsforschung\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/shop.budrich.de\/produkt\/kritische-kinderrechtsforschung\/#primaryimage","url":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2022\/12\/9783847427087-1-scaled.jpg","contentUrl":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2022\/12\/9783847427087-1-scaled.jpg","width":1444,"height":2048},{"@type":"BreadcrumbList","@id":"https:\/\/shop.budrich.de\/produkt\/kritische-kinderrechtsforschung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/shop.budrich.de\/"},{"@type":"ListItem","position":2,"name":"Programm","item":"https:\/\/shop.budrich.de\/shop\/"},{"@type":"ListItem","position":3,"name":"Kritische Kinderrechtsforschung"}]},{"@type":"WebSite","@id":"https:\/\/shop.budrich.de\/#website","url":"https:\/\/shop.budrich.de\/","name":"Verlag Barbara Budrich","description":"Qualitativ hochwertige Publikationen f\u00fcr die Sozial- und Erziehungswissenschaften","publisher":{"@id":"https:\/\/shop.budrich.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/shop.budrich.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/shop.budrich.de\/#organization","name":"Verlag Barbara Budrich GmbH","url":"https:\/\/shop.budrich.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/shop.budrich.de\/#\/schema\/logo\/image\/","url":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2020\/11\/verlag-barbara-budrich-logo.jpg","contentUrl":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2020\/11\/verlag-barbara-budrich-logo.jpg","width":354,"height":354,"caption":"Verlag Barbara Budrich GmbH"},"image":{"@id":"https:\/\/shop.budrich.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product\/136835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/comments?post=136835"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/media\/138458"}],"wp:attachment":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/media?parent=136835"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product_brand?post=136835"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product_cat?post=136835"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product_tag?post=136835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}