{"id":140869,"date":"2024-09-23T03:00:05","date_gmt":"2024-09-23T01:00:05","guid":{"rendered":"https:\/\/shop.budrich.de\/produkt\/schule-migration-uebergang\/"},"modified":"2024-12-16T14:43:48","modified_gmt":"2024-12-16T13:43:48","slug":"schule-migration-uebergang","status":"publish","type":"product","link":"https:\/\/shop.budrich.de\/en\/produkt\/schule-migration-uebergang\/","title":{"rendered":"Schule, Migration, \u00dcbergang"},"content":{"rendered":"<p><b>Der Zugang zu Bildung und damit der \u00dcbergang in das Regelschulsystem findet f\u00fcr neu zugewanderte und gefl\u00fcchtete Kinder und Jugendliche oft durch eine institutionell gerahmte Zwischenphase in Vorbereitungsklassen statt. Aus einer ungleichheitsrelevanten Perspektive rekonstruiert Anna C. Reinhardt in ihrer qualitativen Studie diese Vorbereitungsklassen als komplexe \u00dcbergangssituationen und dekonstruiert ihr relationales Zustandekommen als konflikthaften Aushandlungsprozess um Teilhabe und Zugeh\u00f6rigkeit in der Migrationsgesellschaft.<\/b><\/p>\n<p>Das staatliche Bildungssystem war und ist aufgrund heterogener Migrations- und Fluchtbewegungen kontinuierlich mit der Aufgabe befasst, neu zugewanderte\/gefl\u00fcchtete Kinder und Jugendliche in das Schulsystem zu inkludieren und damit den Zugang zu schulischer Bildung zu erm\u00f6glichen. Bildungspolitisch wird dieses migrationsspezifische \u00dcbergangsph\u00e4nomen vielmals durch die institutionelle Etablierung von sog. Vorbereitungsklassen, altersheterogenen und (teil-)separierten Unterrichtskontexten, bearbeitet. Dadurch wird eine Transitionsphase institutionell hervorgebracht, die einerseits quer zu den schulischen Verlaufskonzepten der Dominanzgesellschaft liegt. Andererseits wird mit dieser Beschulungsform ein \u00dcbergang sozial konstruiert, den ausschlie\u00dflich die (fremd-)kategorisierte \u2018Personengruppe\u2018 der sog. Seiteneinsteiger:innen durchlaufen muss, um in das Regelschulsystem integriert zu werden.\u00a0Die Studie setzt an diesem ungleichheitsrelevanten Transitionsph\u00e4nomen der Vorbereitungsklassen an und erforscht dieses aus einer situationsanalytisch informierten und \u00fcbergangstheoretischen Perspektivierung. Damit wird eine konstruktivistische Lesart eingenommen, die diese \u00dcbergangssituation nicht als quasi-nat\u00fcrliche Gegebenheit versteht, sondern ihre Herstellungspraxis kritisch reflektiert. Ziel dieser Studie ist es dem folgend eine Rekonstruktion des relationalen Zustandekommens \u2013 also wie und durch wen werden diese Vorbereitungsklassen gegenw\u00e4rtig hergestellt und (aus-)gestaltet \u2013 und eine Dekonstruktion dieser institutionell gerahmten \u00dcbergangssituation zu erhalten.\u00a0Im ethnografischen Forschungsprozess war es m\u00f6glich Vorbereitungsklassen an Schulen in Baden-W\u00fcrttemberg zu erkunden und dabei unterschiedliche Daten (z.B. Beobachtungsprotokolle, Dokumente, Interviews) zu erheben und situationsanalytisch zu interpretieren. Dadurch kann zum einen dargelegt werden, wie Vorbereitungsklassen durch ein relationales Zusammenspiel unterschiedlicher Akteursgruppen, Institutionen und Diskursen als symbolische \u00dcbergangssituation hergestellt werden. Diese Situation wird zum anderen f\u00fcr die sog. Seiteneinsteiger:innen im schulischen Kontext zu einer ungleichheitsrelevanten Zwischenphase, in welcher symbolische Zugeh\u00f6rigkeitsordnungen (re-)produziert und konflikthafte Aushandlungsprozesse, um die Frage nach Teilhabe in der Migrationsgesellschaft ausgetragen werden.<\/p>\n<p><strong>Die Autorin:<\/strong><br \/>\n<strong>Dr. Anna C. Reinhardt<\/strong>, wissenschaftliche Mitarbeiterin, Arbeitsbereich Erziehung und Bildung in der Migrationsgesellschaft, Institut f\u00fcr Erziehungswissenschaft, Universit\u00e4t Osnabr\u00fcck<\/p>\n<p><strong>Subjects:<\/strong><br \/>\nErziehungswissenschaft, Soziologie<\/p>","protected":false},"excerpt":{"rendered":"<p>Der Zugang zu Bildung und damit der \u00dcbergang in das Regelschulsystem findet f\u00fcr neu zugewanderte und gefl\u00fcchtete Kinder und Jugendliche oft durch eine institutionell gerahmte Zwischenphase in Vorbereitungsklassen statt. Aus einer ungleichheitsrelevanten Perspektive rekonstruiert Anna C. Reinhardt in ihrer qualitativen Studie diese Vorbereitungsklassen als komplexe \u00dcbergangssituationen und dekonstruiert ihr relationales Zustandekommen als konflikthaften Aushandlungsprozess um [&hellip;]<\/p>\n","protected":false},"featured_media":140870,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[7589,23842,7609],"product_tag":[55257,7590,51898,51899,8142,7712,35766,13710,25986,9043,9549,47587],"class_list":{"0":"post-140869","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_author-anna-c-reinhardt","7":"product_cat-gesellschaft","8":"product_cat-fachbereiche","9":"product_cat-erziehung","10":"product_tag-september-2024","11":"product_tag-migration","12":"product_tag-seiteneinsteigerinnen","13":"product_tag-vorbereitungsklassen","14":"product_tag-uebergang","15":"product_tag-schule","16":"product_tag-bildungssystem","17":"product_tag-flucht","18":"product_tag-situationsanalyse","19":"product_tag-ethnografie","20":"product_tag-grounded-theory","21":"product_tag-bildungsteilhabe","22":"pa_reihe-reflexive-uebergangsforschung-doing-transitions-2","23":"pa_verlag-verlag-barbara-budrich","24":"wpbf-post","27":"instock","28":"taxable","29":"shipping-taxable","30":"purchasable","31":"product-type-variable","32":"has-default-attributes"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Schule, Migration, \u00dcbergang<\/title>\n<meta name=\"description\" content=\"Reinhardt, Eine situationsanalytische Rekonstruktion und theoretische Reflexion zur Beschulung von neu Zugewanderten. Verlag Barbara Budrich. ISBN: 978-3-8474-2526-7. Erscheinungsdatum: 23.09.2024.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/shop.budrich.de\/en\/product-2\/schule-migration-uebergang\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Schule, Migration, \u00dcbergang\" \/>\n<meta property=\"og:description\" content=\"Reinhardt, Eine situationsanalytische Rekonstruktion und theoretische Reflexion zur Beschulung von neu Zugewanderten. Verlag Barbara Budrich. ISBN: 978-3-8474-2526-7. Erscheinungsdatum: 23.09.2024.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/shop.budrich.de\/en\/product-2\/schule-migration-uebergang\/\" \/>\n<meta property=\"og:site_name\" content=\"Verlag Barbara Budrich\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-16T13:43:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/shop.budrich.de\/wp-content\/uploads\/2023\/05\/9783847425267-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1435\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/schule-migration-uebergang\\\/\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/schule-migration-uebergang\\\/\",\"name\":\"Schule, Migration, \u00dcbergang\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/schule-migration-uebergang\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/schule-migration-uebergang\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/9783847425267-scaled.jpg\",\"datePublished\":\"2024-09-23T01:00:05+00:00\",\"dateModified\":\"2024-12-16T13:43:48+00:00\",\"description\":\"Reinhardt, Eine situationsanalytische Rekonstruktion und theoretische Reflexion zur Beschulung von neu Zugewanderten. Verlag Barbara Budrich. ISBN: 978-3-8474-2526-7. Erscheinungsdatum: 23.09.2024.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/schule-migration-uebergang\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/schule-migration-uebergang\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/schule-migration-uebergang\\\/#primaryimage\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/9783847425267-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/9783847425267-scaled.jpg\",\"width\":1435,\"height\":2048},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/schule-migration-uebergang\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/shop.budrich.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Programm\",\"item\":\"https:\\\/\\\/shop.budrich.de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Schule, Migration, \u00dcbergang\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#website\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/\",\"name\":\"Verlag Barbara Budrich\",\"description\":\"Qualitativ hochwertige Publikationen f\u00fcr die Sozial- und Erziehungswissenschaften\",\"publisher\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/shop.budrich.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#organization\",\"name\":\"Verlag Barbara Budrich GmbH\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/verlag-barbara-budrich-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/verlag-barbara-budrich-logo.jpg\",\"width\":354,\"height\":354,\"caption\":\"Verlag Barbara Budrich GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Schule, Migration, \u00dcbergang","description":"Reinhardt, Eine situationsanalytische Rekonstruktion und theoretische Reflexion zur Beschulung von neu Zugewanderten. Verlag Barbara Budrich. ISBN: 978-3-8474-2526-7. Erscheinungsdatum: 23.09.2024.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/shop.budrich.de\/en\/product-2\/schule-migration-uebergang\/","og_locale":"en_US","og_type":"article","og_title":"Schule, Migration, \u00dcbergang","og_description":"Reinhardt, Eine situationsanalytische Rekonstruktion und theoretische Reflexion zur Beschulung von neu Zugewanderten. Verlag Barbara Budrich. ISBN: 978-3-8474-2526-7. Erscheinungsdatum: 23.09.2024.","og_url":"https:\/\/shop.budrich.de\/en\/product-2\/schule-migration-uebergang\/","og_site_name":"Verlag Barbara Budrich","article_modified_time":"2024-12-16T13:43:48+00:00","og_image":[{"width":1435,"height":2048,"url":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2023\/05\/9783847425267-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/shop.budrich.de\/produkt\/schule-migration-uebergang\/","url":"https:\/\/shop.budrich.de\/produkt\/schule-migration-uebergang\/","name":"Schule, Migration, \u00dcbergang","isPartOf":{"@id":"https:\/\/shop.budrich.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/shop.budrich.de\/produkt\/schule-migration-uebergang\/#primaryimage"},"image":{"@id":"https:\/\/shop.budrich.de\/produkt\/schule-migration-uebergang\/#primaryimage"},"thumbnailUrl":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2023\/05\/9783847425267-scaled.jpg","datePublished":"2024-09-23T01:00:05+00:00","dateModified":"2024-12-16T13:43:48+00:00","description":"Reinhardt, Eine situationsanalytische Rekonstruktion und theoretische Reflexion zur Beschulung von neu Zugewanderten. Verlag Barbara Budrich. ISBN: 978-3-8474-2526-7. Erscheinungsdatum: 23.09.2024.","breadcrumb":{"@id":"https:\/\/shop.budrich.de\/produkt\/schule-migration-uebergang\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/shop.budrich.de\/produkt\/schule-migration-uebergang\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/shop.budrich.de\/produkt\/schule-migration-uebergang\/#primaryimage","url":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2023\/05\/9783847425267-scaled.jpg","contentUrl":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2023\/05\/9783847425267-scaled.jpg","width":1435,"height":2048},{"@type":"BreadcrumbList","@id":"https:\/\/shop.budrich.de\/produkt\/schule-migration-uebergang\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/shop.budrich.de\/"},{"@type":"ListItem","position":2,"name":"Programm","item":"https:\/\/shop.budrich.de\/shop\/"},{"@type":"ListItem","position":3,"name":"Schule, Migration, \u00dcbergang"}]},{"@type":"WebSite","@id":"https:\/\/shop.budrich.de\/#website","url":"https:\/\/shop.budrich.de\/","name":"Verlag Barbara Budrich","description":"Qualitativ hochwertige Publikationen f\u00fcr die Sozial- und Erziehungswissenschaften","publisher":{"@id":"https:\/\/shop.budrich.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/shop.budrich.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/shop.budrich.de\/#organization","name":"Verlag Barbara Budrich GmbH","url":"https:\/\/shop.budrich.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/shop.budrich.de\/#\/schema\/logo\/image\/","url":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2020\/11\/verlag-barbara-budrich-logo.jpg","contentUrl":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2020\/11\/verlag-barbara-budrich-logo.jpg","width":354,"height":354,"caption":"Verlag Barbara Budrich GmbH"},"image":{"@id":"https:\/\/shop.budrich.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product\/140869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/comments?post=140869"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/media\/140870"}],"wp:attachment":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/media?parent=140869"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product_brand?post=140869"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product_cat?post=140869"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product_tag?post=140869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}