{"id":147940,"date":"2024-10-23T09:30:22","date_gmt":"2024-10-23T07:30:22","guid":{"rendered":"https:\/\/shop.budrich.de\/?post_type=product&#038;p=147940"},"modified":"2025-01-24T09:36:35","modified_gmt":"2025-01-24T08:36:35","slug":"zrex-2-2024-freie-beitraege","status":"publish","type":"product","link":"https:\/\/shop.budrich.de\/en\/produkt\/zrex-2-2024-freie-beitraege\/","title":{"rendered":"ZRex 2-2024 | Freie Beitr\u00e4ge"},"content":{"rendered":"<p><strong>ZRex \u2013 Zeitschrift f\u00fcr Rechtsextremismusforschung<\/strong><br \/>\n<strong>2-2024: Freie Beitr\u00e4ge<br \/>\n<\/strong><\/p>\n<p><em>Beitr\u00e4ge<br \/>\n<\/em><strong>Andreas Jensen:<\/strong> Wie eine \u201eumgekehrte Psychoanalyse\u201c: \u00dcberlegungen zum Propagandabegriff der Kritischen Theorie und dessen Potenzial f\u00fcr die Rechtsextremismusforschung<br \/>\n<strong>Fiona Kalkstein \/ Marius Dilling:<\/strong> \u201e1989\u201c als Mythos \u2013 Apokalypse als Neuanfang. Eine tiefenhermeneutische Fallanalyse der apokalyptischen Narrative und der Wendebez\u00fcge auf den Corona-Protesten<br \/>\n<strong>Kemal Bozay \/ Mihri \u00d6zdo\u011fan \/ Stefan Borrmann \/ Nikolai Anders:<\/strong> Ungleichwertigkeitsideologien in der Post-Migrationsgesellschaft. Ursachen und Formen des t\u00fcrkischen Rechtsextremismus in Deutschland und ihre Auswirkungen auf t\u00fcrkeist\u00e4mmige Jugendmilieus als Herausforderung f\u00fcr die politische Bildung<br \/>\n<strong>Josephine B. Schmitt \/ Julia R. Winkler:<\/strong> Populistische Stimmen in extremistischen Online-Videos \u2013 eine Inhaltsanalyse von rechtsextremen und islamistischen YouTube-Videos<br \/>\n<strong>Daniel Keil:<\/strong> Europa gegen die EU: Aktualisierungen extrem rechter Europa-Imaginationen in der Krise der EU<br \/>\n<strong>Karina Korneli:<\/strong> Erziehung, Familie und Geschlecht im v\u00f6lkischen Neoliberalismus und v\u00f6lkischen Antikapitalismus<\/p>\n<p><em>Forum<\/em><br \/>\n<strong>Damian Groten \/ Martina Ortner \/ Clarissa Rudolph:<\/strong> Interdisziplin\u00e4re Untersuchungen der extremen Rechten in Bayern \u2013 Start des Forschungsverbundes ForGeRex<\/p>\n<p><em>Rezensionen<\/em><br \/>\n<strong>Benjamin Opratko:<\/strong> Wellgraf, Stefan &amp; Hentschel, Christine (Hrsg.). (2022). Rechtspopulismen der Gegenwart. Kulturwissenschaftliche Irritationen<br \/>\n<strong>Hans-Ulrich Probst:<\/strong> Rhein, Philipp (2023). Rechte Zeitverh\u00e4ltnisse. Eine soziologische Analyse von Endzeitvorstellungen im Rechtspopulismus<br \/>\n<strong>Viktoria Kamuf:<\/strong> Bringt, Friedemann; Mayer, Marion; Warrach, Nora &amp; Lehnert, Esther (Hrsg.). (2023). Beratung zu Rechtsextremismus und Demokratiegef\u00e4hrdung. Konzepte \u2013 Herausforderungen \u2013 intersektionale Perspektiven<br \/>\n<strong>Wolfgang Frindte:<\/strong> Mau, Steffen; Lux, Thomas &amp; Westheuser, Linus (2023). Triggerpunkte. Konsens und Konflikt in der Gegenwartsgesellschaft sowie Mau, Steffen (2024). Ungleich vereint. Warum der Osten anders bleibt<br \/>\n<strong>Stefanie Mayer:<\/strong> Scrinzi, Francesca (2024). The Racialization of Sexism. Men, Women and Gender in the Populist Radical Right (Series: Gender and comparative Politics 10)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Einzelbeitrag-Download<\/strong> (Open Access): <a href=\"http:\/\/zrex.budrich-journals.de\" target=\"_blank\" rel=\"noopener noreferrer\">zrex.budrich-journals.de<\/a><br \/>\nSie k\u00f6nnen sich <a href=\"https:\/\/alert-zrex.budrich.de\/\">hier<\/a> f\u00fcr den <strong>ZRex-Alert <\/strong>anmelden.<\/p>","protected":false},"excerpt":{"rendered":"<p>ZRex \u2013 Zeitschrift f\u00fcr Rechtsextremismusforschung 2-2024: Freie Beitr\u00e4ge Beitr\u00e4ge Andreas Jensen: Wie eine \u201eumgekehrte Psychoanalyse\u201c: \u00dcberlegungen zum Propagandabegriff der Kritischen Theorie und dessen Potenzial f\u00fcr die Rechtsextremismusforschung Fiona Kalkstein \/ Marius Dilling: \u201e1989\u201c als Mythos \u2013 Apokalypse als Neuanfang. Eine tiefenhermeneutische Fallanalyse der apokalyptischen Narrative und der Wendebez\u00fcge auf den Corona-Protesten Kemal Bozay \/ Mihri [&hellip;]<\/p>\n","protected":false},"featured_media":147943,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[12497,13145],"product_tag":[55581,10891,41597,55582,11586,43185,55583,55584,54329,55574,43806,55585,7591,55575,46314,55586,7615,21477,55576,46814,55624,7653,21792,55577,7778,55578,47096,7937,34894,55579,50326,7958,55580,8556],"class_list":{"0":"post-147940","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_author-andreas-jensen","7":"product_author-fiona-kalkstein","8":"product_author-marius-dilling","9":"product_author-kemal-bozay","10":"product_author-mihri-oezdogan","11":"product_author-borrmann-stefan","12":"product_author-nikolai-anders","13":"product_author-josephine-b-schmitt","14":"product_author-julia-r-winkler","15":"product_author-daniel-keil","16":"product_author-karina-korneli","17":"product_author-damian-groten","18":"product_author-martina-ortner","19":"product_author-rudolph-clarissa","20":"product_author-benjamin-opratko","21":"product_author-hans-ulrich-probst","22":"product_author-viktoria-kamuf","23":"product_author-wolfgang-frindte","24":"product_author-mayer-stefanie","25":"product_cat-open-access","26":"product_cat-einzelhefte","27":"product_tag-tuerkeistaemmige-jugendmilieus","28":"product_tag-krise","29":"product_tag-extreme-rechte","30":"product_tag-uelkuecue-bewegung","31":"product_tag-autoritarismus","32":"product_tag-radikalisierungspraevention","33":"product_tag-extremistische-propaganda","34":"product_tag-europa-imaginationen-der-extremen-rechten","35":"product_tag-ungleichwertigkeitsideologien","36":"product_tag-erlebnisangebot","37":"product_tag-verschwoerungsmentalitaet","38":"product_tag-voelkischer-neoliberalismus","39":"product_tag-geschlecht","40":"product_tag-bjoern-hoecke","41":"product_tag-youtube","42":"product_tag-voelkischer-antikapitalismus","43":"product_tag-europaeische-union","44":"product_tag-populismus","45":"product_tag-apokalypse","46":"product_tag-46814","47":"product_tag-oktober-2024","48":"product_tag-familie","49":"product_tag-inhaltsanalyse","50":"product_tag-mythos","51":"product_tag-rechtsextremismus","52":"product_tag-palingenese","53":"product_tag-propaganda","54":"product_tag-europa","55":"product_tag-neue-rechte","56":"product_tag-tuerkischer-rechtsextremismus","57":"product_tag-psychoanalytische-sozialpsychologie","58":"product_tag-erziehung","59":"product_tag-rassistische-einstellungen","60":"product_tag-kritische-theorie","61":"pa_verlag-verlag-barbara-budrich","62":"wpbf-post","65":"instock","66":"taxable","67":"shipping-taxable","68":"purchasable","69":"product-type-variable"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ZRex 2-2024 | Freie Beitr\u00e4ge<\/title>\n<meta name=\"description\" content=\"ISSN 2701-9624 | eISSN 2701-9632 | 4. Jg. 2024 | Oktober 2024 | 140 Seiten | Verlag Barbara Budrich | Wissenschaftliche Fachzeitschrift | Open Access\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/shop.budrich.de\/en\/product-2\/zrex-2-2024-freie-beitraege\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ZRex 2-2024 | Freie Beitr\u00e4ge\" \/>\n<meta property=\"og:description\" content=\"ISSN 2701-9624 | eISSN 2701-9632 | 4. Jg. 2024 | Oktober 2024 | 140 Seiten | Verlag Barbara Budrich | Wissenschaftliche Fachzeitschrift | Open Access\" \/>\n<meta property=\"og:url\" content=\"https:\/\/shop.budrich.de\/en\/product-2\/zrex-2-2024-freie-beitraege\/\" \/>\n<meta property=\"og:site_name\" content=\"Verlag Barbara Budrich\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-24T08:36:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/shop.budrich.de\/wp-content\/uploads\/2024\/09\/2701-9624-2024-2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1454\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/zrex-2-2024-freie-beitraege\\\/\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/zrex-2-2024-freie-beitraege\\\/\",\"name\":\"ZRex 2-2024 | Freie Beitr\u00e4ge\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/zrex-2-2024-freie-beitraege\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/zrex-2-2024-freie-beitraege\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/2701-9624-2024-2-scaled.jpg\",\"datePublished\":\"2024-10-23T07:30:22+00:00\",\"dateModified\":\"2025-01-24T08:36:35+00:00\",\"description\":\"ISSN 2701-9624 | eISSN 2701-9632 | 4. Jg. 2024 | Oktober 2024 | 140 Seiten | Verlag Barbara Budrich | Wissenschaftliche Fachzeitschrift | Open Access\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/zrex-2-2024-freie-beitraege\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/zrex-2-2024-freie-beitraege\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/zrex-2-2024-freie-beitraege\\\/#primaryimage\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/2701-9624-2024-2-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/2701-9624-2024-2-scaled.jpg\",\"width\":1454,\"height\":2048,\"caption\":\"ZRex \u2013 Zeitschrift f\u00fcr Rechtsextremismusforschung 2-2024: Freie Beitr\u00e4ge\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/zrex-2-2024-freie-beitraege\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/shop.budrich.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Programm\",\"item\":\"https:\\\/\\\/shop.budrich.de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ZRex 2-2024 | Freie Beitr\u00e4ge\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#website\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/\",\"name\":\"Verlag Barbara Budrich\",\"description\":\"Qualitativ hochwertige Publikationen f\u00fcr die Sozial- und Erziehungswissenschaften\",\"publisher\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/shop.budrich.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#organization\",\"name\":\"Verlag Barbara Budrich GmbH\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/verlag-barbara-budrich-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/verlag-barbara-budrich-logo.jpg\",\"width\":354,\"height\":354,\"caption\":\"Verlag Barbara Budrich GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ZRex 2-2024 | Freie Beitr\u00e4ge","description":"ISSN 2701-9624 | eISSN 2701-9632 | 4. Jg. 2024 | Oktober 2024 | 140 Seiten | Verlag Barbara Budrich | Wissenschaftliche Fachzeitschrift | Open Access","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/shop.budrich.de\/en\/product-2\/zrex-2-2024-freie-beitraege\/","og_locale":"en_US","og_type":"article","og_title":"ZRex 2-2024 | Freie Beitr\u00e4ge","og_description":"ISSN 2701-9624 | eISSN 2701-9632 | 4. Jg. 2024 | Oktober 2024 | 140 Seiten | Verlag Barbara Budrich | Wissenschaftliche Fachzeitschrift | Open Access","og_url":"https:\/\/shop.budrich.de\/en\/product-2\/zrex-2-2024-freie-beitraege\/","og_site_name":"Verlag Barbara Budrich","article_modified_time":"2025-01-24T08:36:35+00:00","og_image":[{"width":1454,"height":2048,"url":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2024\/09\/2701-9624-2024-2-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/shop.budrich.de\/produkt\/zrex-2-2024-freie-beitraege\/","url":"https:\/\/shop.budrich.de\/produkt\/zrex-2-2024-freie-beitraege\/","name":"ZRex 2-2024 | Freie Beitr\u00e4ge","isPartOf":{"@id":"https:\/\/shop.budrich.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/shop.budrich.de\/produkt\/zrex-2-2024-freie-beitraege\/#primaryimage"},"image":{"@id":"https:\/\/shop.budrich.de\/produkt\/zrex-2-2024-freie-beitraege\/#primaryimage"},"thumbnailUrl":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2024\/09\/2701-9624-2024-2-scaled.jpg","datePublished":"2024-10-23T07:30:22+00:00","dateModified":"2025-01-24T08:36:35+00:00","description":"ISSN 2701-9624 | eISSN 2701-9632 | 4. Jg. 2024 | Oktober 2024 | 140 Seiten | Verlag Barbara Budrich | Wissenschaftliche Fachzeitschrift | Open Access","breadcrumb":{"@id":"https:\/\/shop.budrich.de\/produkt\/zrex-2-2024-freie-beitraege\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/shop.budrich.de\/produkt\/zrex-2-2024-freie-beitraege\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/shop.budrich.de\/produkt\/zrex-2-2024-freie-beitraege\/#primaryimage","url":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2024\/09\/2701-9624-2024-2-scaled.jpg","contentUrl":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2024\/09\/2701-9624-2024-2-scaled.jpg","width":1454,"height":2048,"caption":"ZRex \u2013 Zeitschrift f\u00fcr Rechtsextremismusforschung 2-2024: Freie Beitr\u00e4ge"},{"@type":"BreadcrumbList","@id":"https:\/\/shop.budrich.de\/produkt\/zrex-2-2024-freie-beitraege\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/shop.budrich.de\/"},{"@type":"ListItem","position":2,"name":"Programm","item":"https:\/\/shop.budrich.de\/shop\/"},{"@type":"ListItem","position":3,"name":"ZRex 2-2024 | Freie Beitr\u00e4ge"}]},{"@type":"WebSite","@id":"https:\/\/shop.budrich.de\/#website","url":"https:\/\/shop.budrich.de\/","name":"Verlag Barbara Budrich","description":"Qualitativ hochwertige Publikationen f\u00fcr die Sozial- und Erziehungswissenschaften","publisher":{"@id":"https:\/\/shop.budrich.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/shop.budrich.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/shop.budrich.de\/#organization","name":"Verlag Barbara Budrich GmbH","url":"https:\/\/shop.budrich.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/shop.budrich.de\/#\/schema\/logo\/image\/","url":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2020\/11\/verlag-barbara-budrich-logo.jpg","contentUrl":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2020\/11\/verlag-barbara-budrich-logo.jpg","width":354,"height":354,"caption":"Verlag Barbara Budrich GmbH"},"image":{"@id":"https:\/\/shop.budrich.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product\/147940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/comments?post=147940"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/media\/147943"}],"wp:attachment":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/media?parent=147940"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product_brand?post=147940"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product_cat?post=147940"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product_tag?post=147940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}