{"id":14840,"date":"2013-12-17T15:57:00","date_gmt":"2013-12-17T14:57:25","guid":{"rendered":"http:\/\/shop.budrich-academic.de\/produkt\/vergangenheit-als-gegenwart-zum-40-jaehrigen-bestehen-der-sektion-erwachsenenbildung-der-dgfe\/"},"modified":"2026-06-05T17:55:07","modified_gmt":"2026-06-05T15:55:07","slug":"vergangenheit-als-gegenwart-zum-40-jaehrigen-bestehen-der-sektion-erwachsenenbildung-der-dgfe","status":"publish","type":"product","link":"https:\/\/shop.budrich.de\/en\/produkt\/vergangenheit-als-gegenwart-zum-40-jaehrigen-bestehen-der-sektion-erwachsenenbildung-der-dgfe\/","title":{"rendered":"Vergangenheit als Gegenwart &#8211; Zum 40-j\u00e4hrigen Bestehen der Sektion Erwachsenenbildung der DGfE"},"content":{"rendered":"<p><strong>Open Access:<\/strong> <em>Der Titel\u00a0<\/em><a href=\"https:\/\/shop.budrich.de\/wp-content\/uploads\/2020\/12\/9783847404941.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><em>Vergangenheit als Gegenwart &#8211; Zum 40-j\u00e4hrigen Bestehen der Sektion Erwachsenenbildung der DGfE (DOI: 10.3224\/84740100) ist <strong>kostenlos im Open Access<\/strong> (PDF)<\/em><\/a><em> herunterladbar oder kostenpflichtig als Print-Ausgabe erh\u00e4ltlich. <\/em><em>Der Titel steht unter der Creative Commons Lizenz Attribution-ShareAlike 4.0 International<\/em><span class=\"cc-license-identifier\">(CC BY 4.0)<\/span><em>: <\/em><a href=\"https:\/\/creativecommons.org\/licenses\/by\/4.0\/\"><em>https:\/\/creativecommons.org\/licenses\/by-sa\/4.0\/<\/em><\/a><\/p>\n<p><strong>Der Band versammelt teils unver\u00f6ffentlichte Dokumente zur DGfE-Sektion Erwachsenenbildung, der ersten wissenschaftlichen Fachgesellschaft der Erwachsenenbildung in der Bundesrepublik Deutschland. Darstellungen aus Akten und Protokollen, aus Arbeitsberichten der jeweiligen Vorst\u00e4nde, Briefwechseln, Stellungnahmen, sowie erg\u00e4nzenden Zeitzeugenberichten und Erinnerungen einzelner ProtagonistInnen lassen wichtige Schritte der Professionalisierung, Akademisierung und Etablierung der Erwachsenenbildung in Deutschland erkennen.<\/strong><\/p>\n<p><a href=\"http:\/\/shop.budrich-academic.de\/wp-content\/uploads\/shop-inhalt\/9783847401001_iv.pdf\">Inhaltsverzeichnis ansehen<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Die Autorin:<br \/>\nProf. Dr. habil. Sabine Schmidt-Lauff,<\/strong><\/p>\n<p>Technische Universit\u00e4t Chemnitz, Lehrstuhl f\u00fcr Erwachsenenbildung und Weiterbildung, Vorsitzende und Sprecherin der Sektion Erwachsenenbildung der DGfE<\/p>\n<p>&nbsp;<\/p>\n<p>Hier finden Sie den <a href=\"https:\/\/shop.budrich.de\/wp-content\/uploads\/2015\/10\/0100-schmidt-lauff.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Waschzettel<\/a> zum Buch (pdf- Infoblatt).<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Zielgruppen:<\/strong> Mitglieder der Sektion Erwachsenenbildung der DGfE, PraktikerInnen in der Erwachsenenbildung und Weiterbildung<\/p>","protected":false},"excerpt":{"rendered":"<p>Open Access: Der Titel\u00a0Vergangenheit als Gegenwart &#8211; Zum 40-j\u00e4hrigen Bestehen der Sektion Erwachsenenbildung der DGfE (DOI: 10.3224\/84740100) ist kostenlos im Open Access (PDF) herunterladbar oder kostenpflichtig als Print-Ausgabe erh\u00e4ltlich. Der Titel steht unter der Creative Commons Lizenz Attribution-ShareAlike 4.0 International(CC BY 4.0): https:\/\/creativecommons.org\/licenses\/by-sa\/4.0\/ Der Band versammelt teils unver\u00f6ffentlichte Dokumente zur DGfE-Sektion Erwachsenenbildung, der ersten wissenschaftlichen [&hellip;]<\/p>\n","protected":false},"featured_media":18960,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[12497,7609],"product_tag":[8610,7892,8409],"class_list":["post-14840","product","type-product","status-publish","has-post-thumbnail","product_author-schmidt-lauff","product_author-sabine","product_cat-open-access","product_cat-erziehung","product_tag-wissenschaftsgeschichte","product_tag-weiterbildung","product_tag-erwachsenenbildung","pa_reihe-schriftenreihe-der-sektion-erwachsenenbildung-der-deutschen-gesellschaft-fuer-erziehungswissenschaft-dgfe","pa_verlag-verlag-barbara-budrich","wpbf-post","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vergangenheit als Gegenwart - Zum 40-j\u00e4hrigen Bestehen der Sektion Erwachsenenbildung der DGfE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/shop.budrich.de\/en\/product-2\/vergangenheit-als-gegenwart-zum-40-jaehrigen-bestehen-der-sektion-erwachsenenbildung-der-dgfe\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vergangenheit als Gegenwart - Zum 40-j\u00e4hrigen Bestehen der Sektion Erwachsenenbildung der DGfE\" \/>\n<meta property=\"og:description\" content=\"Open Access: Der Titel\u00a0Vergangenheit als Gegenwart &#8211; Zum 40-j\u00e4hrigen Bestehen der Sektion Erwachsenenbildung der DGfE (DOI: 10.3224\/84740100) ist kostenlos im Open Access (PDF) herunterladbar oder kostenpflichtig als Print-Ausgabe erh\u00e4ltlich. Der Titel steht unter der Creative Commons Lizenz Attribution-ShareAlike 4.0 International(CC BY 4.0): https:\/\/creativecommons.org\/licenses\/by-sa\/4.0\/ Der Band versammelt teils unver\u00f6ffentlichte Dokumente zur DGfE-Sektion Erwachsenenbildung, der ersten wissenschaftlichen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/shop.budrich.de\/en\/product-2\/vergangenheit-als-gegenwart-zum-40-jaehrigen-bestehen-der-sektion-erwachsenenbildung-der-dgfe\/\" \/>\n<meta property=\"og:site_name\" content=\"Verlag Barbara Budrich\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-05T15:55:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/shop.budrich.de\/wp-content\/uploads\/2015\/10\/97838474010019.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"417\" \/>\n\t<meta property=\"og:image:height\" content=\"590\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/vergangenheit-als-gegenwart-zum-40-jaehrigen-bestehen-der-sektion-erwachsenenbildung-der-dgfe\\\/\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/vergangenheit-als-gegenwart-zum-40-jaehrigen-bestehen-der-sektion-erwachsenenbildung-der-dgfe\\\/\",\"name\":\"Vergangenheit als Gegenwart - Zum 40-j\u00e4hrigen Bestehen der Sektion Erwachsenenbildung der DGfE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/vergangenheit-als-gegenwart-zum-40-jaehrigen-bestehen-der-sektion-erwachsenenbildung-der-dgfe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/vergangenheit-als-gegenwart-zum-40-jaehrigen-bestehen-der-sektion-erwachsenenbildung-der-dgfe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/97838474010019.jpg\",\"datePublished\":\"2013-12-17T14:57:25+00:00\",\"dateModified\":\"2026-06-05T15:55:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/vergangenheit-als-gegenwart-zum-40-jaehrigen-bestehen-der-sektion-erwachsenenbildung-der-dgfe\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/vergangenheit-als-gegenwart-zum-40-jaehrigen-bestehen-der-sektion-erwachsenenbildung-der-dgfe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/vergangenheit-als-gegenwart-zum-40-jaehrigen-bestehen-der-sektion-erwachsenenbildung-der-dgfe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/97838474010019.jpg\",\"contentUrl\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/97838474010019.jpg\",\"width\":417,\"height\":590},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/vergangenheit-als-gegenwart-zum-40-jaehrigen-bestehen-der-sektion-erwachsenenbildung-der-dgfe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/shop.budrich.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Programm\",\"item\":\"https:\\\/\\\/shop.budrich.de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vergangenheit als Gegenwart &#8211; Zum 40-j\u00e4hrigen Bestehen der Sektion Erwachsenenbildung der DGfE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#website\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/\",\"name\":\"Verlag Barbara Budrich\",\"description\":\"Qualitativ hochwertige Publikationen f\u00fcr die Sozial- und Erziehungswissenschaften\",\"publisher\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/shop.budrich.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#organization\",\"name\":\"Verlag Barbara Budrich GmbH\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/verlag-barbara-budrich-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/verlag-barbara-budrich-logo.jpg\",\"width\":354,\"height\":354,\"caption\":\"Verlag Barbara Budrich GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vergangenheit als Gegenwart - Zum 40-j\u00e4hrigen Bestehen der Sektion Erwachsenenbildung der DGfE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/shop.budrich.de\/en\/product-2\/vergangenheit-als-gegenwart-zum-40-jaehrigen-bestehen-der-sektion-erwachsenenbildung-der-dgfe\/","og_locale":"en_US","og_type":"article","og_title":"Vergangenheit als Gegenwart - Zum 40-j\u00e4hrigen Bestehen der Sektion Erwachsenenbildung der DGfE","og_description":"Open Access: Der Titel\u00a0Vergangenheit als Gegenwart &#8211; Zum 40-j\u00e4hrigen Bestehen der Sektion Erwachsenenbildung der DGfE (DOI: 10.3224\/84740100) ist kostenlos im Open Access (PDF) herunterladbar oder kostenpflichtig als Print-Ausgabe erh\u00e4ltlich. Der Titel steht unter der Creative Commons Lizenz Attribution-ShareAlike 4.0 International(CC BY 4.0): https:\/\/creativecommons.org\/licenses\/by-sa\/4.0\/ Der Band versammelt teils unver\u00f6ffentlichte Dokumente zur DGfE-Sektion Erwachsenenbildung, der ersten wissenschaftlichen [&hellip;]","og_url":"https:\/\/shop.budrich.de\/en\/product-2\/vergangenheit-als-gegenwart-zum-40-jaehrigen-bestehen-der-sektion-erwachsenenbildung-der-dgfe\/","og_site_name":"Verlag Barbara Budrich","article_modified_time":"2026-06-05T15:55:07+00:00","og_image":[{"width":417,"height":590,"url":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2015\/10\/97838474010019.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/shop.budrich.de\/produkt\/vergangenheit-als-gegenwart-zum-40-jaehrigen-bestehen-der-sektion-erwachsenenbildung-der-dgfe\/","url":"https:\/\/shop.budrich.de\/produkt\/vergangenheit-als-gegenwart-zum-40-jaehrigen-bestehen-der-sektion-erwachsenenbildung-der-dgfe\/","name":"Vergangenheit als Gegenwart - Zum 40-j\u00e4hrigen Bestehen der Sektion Erwachsenenbildung der DGfE","isPartOf":{"@id":"https:\/\/shop.budrich.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/shop.budrich.de\/produkt\/vergangenheit-als-gegenwart-zum-40-jaehrigen-bestehen-der-sektion-erwachsenenbildung-der-dgfe\/#primaryimage"},"image":{"@id":"https:\/\/shop.budrich.de\/produkt\/vergangenheit-als-gegenwart-zum-40-jaehrigen-bestehen-der-sektion-erwachsenenbildung-der-dgfe\/#primaryimage"},"thumbnailUrl":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2015\/10\/97838474010019.jpg","datePublished":"2013-12-17T14:57:25+00:00","dateModified":"2026-06-05T15:55:07+00:00","breadcrumb":{"@id":"https:\/\/shop.budrich.de\/produkt\/vergangenheit-als-gegenwart-zum-40-jaehrigen-bestehen-der-sektion-erwachsenenbildung-der-dgfe\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/shop.budrich.de\/produkt\/vergangenheit-als-gegenwart-zum-40-jaehrigen-bestehen-der-sektion-erwachsenenbildung-der-dgfe\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/shop.budrich.de\/produkt\/vergangenheit-als-gegenwart-zum-40-jaehrigen-bestehen-der-sektion-erwachsenenbildung-der-dgfe\/#primaryimage","url":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2015\/10\/97838474010019.jpg","contentUrl":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2015\/10\/97838474010019.jpg","width":417,"height":590},{"@type":"BreadcrumbList","@id":"https:\/\/shop.budrich.de\/produkt\/vergangenheit-als-gegenwart-zum-40-jaehrigen-bestehen-der-sektion-erwachsenenbildung-der-dgfe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/shop.budrich.de\/"},{"@type":"ListItem","position":2,"name":"Programm","item":"https:\/\/shop.budrich.de\/shop\/"},{"@type":"ListItem","position":3,"name":"Vergangenheit als Gegenwart &#8211; Zum 40-j\u00e4hrigen Bestehen der Sektion Erwachsenenbildung der DGfE"}]},{"@type":"WebSite","@id":"https:\/\/shop.budrich.de\/#website","url":"https:\/\/shop.budrich.de\/","name":"Verlag Barbara Budrich","description":"Qualitativ hochwertige Publikationen f\u00fcr die Sozial- und Erziehungswissenschaften","publisher":{"@id":"https:\/\/shop.budrich.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/shop.budrich.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/shop.budrich.de\/#organization","name":"Verlag Barbara Budrich GmbH","url":"https:\/\/shop.budrich.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/shop.budrich.de\/#\/schema\/logo\/image\/","url":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2020\/11\/verlag-barbara-budrich-logo.jpg","contentUrl":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2020\/11\/verlag-barbara-budrich-logo.jpg","width":354,"height":354,"caption":"Verlag Barbara Budrich GmbH"},"image":{"@id":"https:\/\/shop.budrich.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product\/14840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/comments?post=14840"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/media\/18960"}],"wp:attachment":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/media?parent=14840"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product_brand?post=14840"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product_cat?post=14840"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product_tag?post=14840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}