{"id":15946,"date":"2011-06-09T15:57:00","date_gmt":"2011-06-09T14:57:28","guid":{"rendered":"http:\/\/shop.budrich-academic.de\/produkt\/lehr-lernforschung-und-professionalisierung\/"},"modified":"2021-10-11T13:24:13","modified_gmt":"2021-10-11T11:24:13","slug":"lehr-lernforschung-und-professionalisierung","status":"publish","type":"product","link":"https:\/\/shop.budrich.de\/en\/produkt\/lehr-lernforschung-und-professionalisierung\/","title":{"rendered":"Lehr-Lernforschung und Professionalisierung"},"content":{"rendered":"<p><em><strong>Open Access: <\/strong><\/em><em>Dieser Titel ist <a href=\"https:\/\/shop.budrich.de\/wp-content\/uploads\/2015\/10\/9783866496248.pdf\" target=\"_blank\" rel=\"noopener\" data-wpel-link=\"internal\">kostenlos im Open Access herunterladbar (PDF)<\/a> oder kostenpflichtig als Print-Ausgabe erh\u00e4ltlich.<\/em><\/p>\n<p><strong>Die Themenschwerpunkte Lehr-Lern-Forschung und Professionalisierung werden aus Sicht aktueller Forschungsprojekte sowohl empirisch als auch theoretisch analysiert. Im Vordergrund stehen die Wirksamkeit spezifischer Unterrichtsmethoden und F\u00f6rderma\u00dfnahmen sowie professionelle Kompetenzen des Bildungspersonals.<\/strong><\/p>\n<p><strong>Die Herausgeber*innen:<br \/>\nProf. Dr. Uwe Fa\u00dfhauer, <\/strong>Professor an der P\u00e4dagogischen Hochschule Schw\u00e4bisch Gm\u00fcnd<br \/>\n<strong>Prof. Dr. Josef Aff, <\/strong>Professor an der Wirtschaftsuniversit\u00e4t Wien<br \/>\n<strong>Prof. Dr. B\u00e4rbel F\u00fcrstenau, <\/strong>Professor an der Technischen Universit\u00e4t Dresden<br \/>\n<strong>Prof. Dr. Eveline Wuttke, <\/strong>Professorin an der Goethe-Universit\u00e4t Frankfurt<\/p>\n<p>Webseite der Sektion \u201e<a href=\"https:\/\/www.dgfe.de\/sektionen-kommissionen-ag\/sektion-7-berufs-und-wirtschaftspaedagogik\" target=\"_blank\" rel=\"noopener\">Berufs- und Wirtschaftsp\u00e4dagogik<\/a>\u201c (BWP) der <a class=\"external-link-new-window\" title=\"Homepage DGfE\" href=\"http:\/\/www.dgfe.de\/\" target=\"_blank\" rel=\"noopener\">Deutschen Gesellschaft f\u00fcr Erziehungswissenschaft<\/a> (DGfE).<\/p>","protected":false},"excerpt":{"rendered":"<p>Open Access: Dieser Titel ist kostenlos im Open Access herunterladbar (PDF) oder kostenpflichtig als Print-Ausgabe erh\u00e4ltlich. Die Themenschwerpunkte Lehr-Lern-Forschung und Professionalisierung werden aus Sicht aktueller Forschungsprojekte sowohl empirisch als auch theoretisch analysiert. Im Vordergrund stehen die Wirksamkeit spezifischer Unterrichtsmethoden und F\u00f6rderma\u00dfnahmen sowie professionelle Kompetenzen des Bildungspersonals. Die Herausgeber*innen: Prof. Dr. Uwe Fa\u00dfhauer, Professor an der [&hellip;]<\/p>\n","protected":false},"featured_media":19183,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[12497,7609],"product_tag":[9482,7884,8749],"class_list":{"0":"post-15946","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_author-fasshauer-uwe","7":"product_author-fuerstenau-baerbel","8":"product_author-aff-josef","9":"product_author-wuttke-eveline","10":"product_cat-open-access","11":"product_cat-erziehung","12":"product_tag-kompetenzentwicklung","13":"product_tag-berufspaedagogik","14":"product_tag-wirtschaftspaedagogik","15":"pa_reihe-schriftenreihe-der-sektion-berufs-und-wirtschaftspaedagogik-der-deutschen-gesellschaft-fuer-erziehungswissenschaft-dgfe","16":"pa_verlag-verlag-barbara-budrich","17":"wpbf-post","20":"instock","21":"taxable","22":"shipping-taxable","23":"purchasable","24":"product-type-variable"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lehr-Lernforschung und Professionalisierung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/shop.budrich.de\/en\/product-2\/lehr-lernforschung-und-professionalisierung\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lehr-Lernforschung und Professionalisierung\" \/>\n<meta property=\"og:description\" content=\"Open Access: Dieser Titel ist kostenlos im Open Access herunterladbar (PDF) oder kostenpflichtig als Print-Ausgabe erh\u00e4ltlich. Die Themenschwerpunkte Lehr-Lern-Forschung und Professionalisierung werden aus Sicht aktueller Forschungsprojekte sowohl empirisch als auch theoretisch analysiert. Im Vordergrund stehen die Wirksamkeit spezifischer Unterrichtsmethoden und F\u00f6rderma\u00dfnahmen sowie professionelle Kompetenzen des Bildungspersonals. Die Herausgeber*innen: Prof. Dr. Uwe Fa\u00dfhauer, Professor an der [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/shop.budrich.de\/en\/product-2\/lehr-lernforschung-und-professionalisierung\/\" \/>\n<meta property=\"og:site_name\" content=\"Verlag Barbara Budrich\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-11T11:24:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/shop.budrich.de\/wp-content\/uploads\/2015\/10\/97838664936749.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"456\" \/>\n\t<meta property=\"og:image:height\" content=\"648\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/lehr-lernforschung-und-professionalisierung\\\/\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/lehr-lernforschung-und-professionalisierung\\\/\",\"name\":\"Lehr-Lernforschung und Professionalisierung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/lehr-lernforschung-und-professionalisierung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/lehr-lernforschung-und-professionalisierung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/97838664936749.jpg\",\"datePublished\":\"2011-06-09T14:57:28+00:00\",\"dateModified\":\"2021-10-11T11:24:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/lehr-lernforschung-und-professionalisierung\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/lehr-lernforschung-und-professionalisierung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/lehr-lernforschung-und-professionalisierung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/97838664936749.jpg\",\"contentUrl\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/97838664936749.jpg\",\"width\":456,\"height\":648},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/lehr-lernforschung-und-professionalisierung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/shop.budrich.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Programm\",\"item\":\"https:\\\/\\\/shop.budrich.de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lehr-Lernforschung und Professionalisierung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#website\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/\",\"name\":\"Verlag Barbara Budrich\",\"description\":\"Qualitativ hochwertige Publikationen f\u00fcr die Sozial- und Erziehungswissenschaften\",\"publisher\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/shop.budrich.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#organization\",\"name\":\"Verlag Barbara Budrich GmbH\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/verlag-barbara-budrich-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/verlag-barbara-budrich-logo.jpg\",\"width\":354,\"height\":354,\"caption\":\"Verlag Barbara Budrich GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lehr-Lernforschung und Professionalisierung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/shop.budrich.de\/en\/product-2\/lehr-lernforschung-und-professionalisierung\/","og_locale":"en_US","og_type":"article","og_title":"Lehr-Lernforschung und Professionalisierung","og_description":"Open Access: Dieser Titel ist kostenlos im Open Access herunterladbar (PDF) oder kostenpflichtig als Print-Ausgabe erh\u00e4ltlich. Die Themenschwerpunkte Lehr-Lern-Forschung und Professionalisierung werden aus Sicht aktueller Forschungsprojekte sowohl empirisch als auch theoretisch analysiert. Im Vordergrund stehen die Wirksamkeit spezifischer Unterrichtsmethoden und F\u00f6rderma\u00dfnahmen sowie professionelle Kompetenzen des Bildungspersonals. Die Herausgeber*innen: Prof. Dr. Uwe Fa\u00dfhauer, Professor an der [&hellip;]","og_url":"https:\/\/shop.budrich.de\/en\/product-2\/lehr-lernforschung-und-professionalisierung\/","og_site_name":"Verlag Barbara Budrich","article_modified_time":"2021-10-11T11:24:13+00:00","og_image":[{"width":456,"height":648,"url":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2015\/10\/97838664936749.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/shop.budrich.de\/produkt\/lehr-lernforschung-und-professionalisierung\/","url":"https:\/\/shop.budrich.de\/produkt\/lehr-lernforschung-und-professionalisierung\/","name":"Lehr-Lernforschung und Professionalisierung","isPartOf":{"@id":"https:\/\/shop.budrich.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/shop.budrich.de\/produkt\/lehr-lernforschung-und-professionalisierung\/#primaryimage"},"image":{"@id":"https:\/\/shop.budrich.de\/produkt\/lehr-lernforschung-und-professionalisierung\/#primaryimage"},"thumbnailUrl":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2015\/10\/97838664936749.jpg","datePublished":"2011-06-09T14:57:28+00:00","dateModified":"2021-10-11T11:24:13+00:00","breadcrumb":{"@id":"https:\/\/shop.budrich.de\/produkt\/lehr-lernforschung-und-professionalisierung\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/shop.budrich.de\/produkt\/lehr-lernforschung-und-professionalisierung\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/shop.budrich.de\/produkt\/lehr-lernforschung-und-professionalisierung\/#primaryimage","url":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2015\/10\/97838664936749.jpg","contentUrl":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2015\/10\/97838664936749.jpg","width":456,"height":648},{"@type":"BreadcrumbList","@id":"https:\/\/shop.budrich.de\/produkt\/lehr-lernforschung-und-professionalisierung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/shop.budrich.de\/"},{"@type":"ListItem","position":2,"name":"Programm","item":"https:\/\/shop.budrich.de\/shop\/"},{"@type":"ListItem","position":3,"name":"Lehr-Lernforschung und Professionalisierung"}]},{"@type":"WebSite","@id":"https:\/\/shop.budrich.de\/#website","url":"https:\/\/shop.budrich.de\/","name":"Verlag Barbara Budrich","description":"Qualitativ hochwertige Publikationen f\u00fcr die Sozial- und Erziehungswissenschaften","publisher":{"@id":"https:\/\/shop.budrich.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/shop.budrich.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/shop.budrich.de\/#organization","name":"Verlag Barbara Budrich GmbH","url":"https:\/\/shop.budrich.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/shop.budrich.de\/#\/schema\/logo\/image\/","url":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2020\/11\/verlag-barbara-budrich-logo.jpg","contentUrl":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2020\/11\/verlag-barbara-budrich-logo.jpg","width":354,"height":354,"caption":"Verlag Barbara Budrich GmbH"},"image":{"@id":"https:\/\/shop.budrich.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product\/15946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/comments?post=15946"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/media\/19183"}],"wp:attachment":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/media?parent=15946"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product_brand?post=15946"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product_cat?post=15946"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product_tag?post=15946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}