{"id":17485,"date":"2006-03-27T15:40:00","date_gmt":"2006-03-27T14:40:23","guid":{"rendered":"http:\/\/shop.budrich-academic.de\/produkt\/bundeswehr-die-naechsten-50-jahre\/"},"modified":"2021-02-26T13:10:09","modified_gmt":"2021-02-26T12:10:09","slug":"bundeswehr-die-naechsten-50-jahre","status":"publish","type":"product","link":"https:\/\/shop.budrich.de\/en\/produkt\/bundeswehr-die-naechsten-50-jahre\/","title":{"rendered":"Bundeswehr &#8211; Die n\u00e4chsten 50 Jahre"},"content":{"rendered":"<p><strong>Die Bundeswehr ist eines der wichtigen Instrumente deutscher Au\u00dfen- und Sicherheitspolitik, und befindet sich in einem Prozess der permanenten Ver\u00e4nderung an gewandelte Aufgaben. Die klassischen Aufgaben von Streitkr\u00e4ften werden in Zukunft vermehrt durch neue Anforderungen und Herausforderungen ersetzt werden. Der Band untersucht die unterschiedlichen Aspekte der zuk\u00fcnftigen Aufgaben und ben\u00f6tigten F\u00e4higkeiten der Bundeswehr f\u00fcr das 21. Jahrhundert, von der zivilmilit\u00e4rischen Zusammenarbeit bis zum Peace-Enforcement.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Aus dem Inhalt:<\/strong><\/p>\n<p><strong>I. Konzeptionelle Grundlagen<\/strong><\/p>\n<p>Joachim Krause, Sicherheitspolitische Herausforderungen im 21. Jahrhundert und die Aufgaben von Streitkr\u00e4ften<\/p>\n<p>Jennifer Assmann, Konzeptionelle Vorgaben durch internationale Einbindung: Europ\u00e4ische Sicherheitsstrategie, Aufgabensetzung der NATO, Mitwirkung im Rahmen der VN<\/p>\n<p>Ernst-Christoph Meier, Die Verteidigungspolitischen Richtlinien der Bundeswehr im Spannungsfeld zwischen internationalen Anforderungen und nationalen Beschr\u00e4nkungen<\/p>\n<p>Klaus Wittmann, Berufsarmee oder Wehrpflicht \u2013 was braucht die Bundeswehr?<\/p>\n<p><strong>II. <\/strong><strong>Die multinationale Einbindung der Bundeswehr<\/strong><\/p>\n<p>Svenja Sinjen, Die Bundeswehr und die Aufgaben der Atlantischen Allianz<\/p>\n<p>Johannes Varwick, Die Bundeswehr als Teil einer europ\u00e4ischen Eingreiftruppe<\/p>\n<p>Manuel Fr\u00f6hlich\/ Ekkehard Griep, Die Bundeswehr als bewaffneter Arm der Vereinten Nationen?<\/p>\n<p><strong>\u00a0III. Die Reform der Bundeswehr<\/strong><\/p>\n<p>Roland K\u00e4stner, Die Bundeswehr im Jahre 2020 \u2013 \u00dcberlegungen zur Strukturreform<\/p>\n<p>Patrick Fitschen, Vernetzte Operationsf\u00fchrung als leitendes Prinzip der Streitkr\u00e4ftereform \u2013 Konsequenzen f\u00fcr die Bundeswehrreform<\/p>\n<p>Benjamin Schreer, Die Entwicklung der Heereskapazit\u00e4ten<\/p>\n<p>Hajo Lippke, Die Entwicklung der maritimen Kapazit\u00e4ten<\/p>\n<p>Martin Ag\u00fcerra, Die Entwicklung der luftgest\u00fctzten F\u00e4higkeiten<\/p>\n<p><strong>IV. <\/strong><strong>Bundeswehr im Einsatz<\/strong><\/p>\n<p>Lutz Holl\u00e4nder, Auslandseins\u00e4tze der Bundeswehr: Bilanz und Perspektive<\/p>\n<p>Jan Irlenkaeuser, Zivil-milit\u00e4rische Zusammenarbeit und \u201eNation Building\u201c<\/p>\n<p>Wilhelm Knelangen, Bundeswehr und die Bek\u00e4mpfung des islamistischen Terrorismus \u2013 das Zusammenwirken von Bundeswehr, Grenzschutz, Polizei und Innenministerien<\/p>\n<p><strong>\u00a0V. <\/strong><strong>Die materiellen Grundlagen f\u00fcr Streitkr\u00e4fte im 21. Jahrhundert<\/strong><\/p>\n<p>Daniel Sattler, Die Kosten der Bundeswehr und deren Finanzierung durch den Bundeshaushalt: Probleme, Perspektiven, Spielr\u00e4ume<\/p>\n<p>Christoph Grams, Die Bereitstellung wehrtechnischer Kapazit\u00e4ten unter Bedingungen abnehmender Haushaltsmittel und zunehmender Europ\u00e4isierung<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Zielgruppe(n)<\/strong>: Wissenschaft, Verwaltung und Bundeswehr<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Die Herausgeber:<\/strong><\/p>\n<p><strong>Prof. Dr. Joachim Krause,<\/strong><\/p>\n<p><strong>Dr. Jan C. Irlenkaeuser,<\/strong> Wissenschaftlicher Mitarbeiter, beide: Institut f\u00fcr Politische Wissenschaft der Christian-Albrechts-Universit\u00e4t zu Kiel<\/p>","protected":false},"excerpt":{"rendered":"<p>Joachim Krause<br \/>\nJan C. Irlenk\u00e4user(Hrsg.)<br \/>\nBundeswehr &#8211; Die n\u00e4chsten 50 Jahre<br \/>\nAnforderungen an deutsche Streitkr\u00e4fte im 21. Jahrhun\u00addert.<br \/>\n2006. 314 S. Kt. 36,00 \u0080 (D), 37,10 \u0080 (A)<\/p>","protected":false},"featured_media":19532,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[7585],"product_tag":[8205,8206,10669],"class_list":{"0":"post-17485","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_author-krause-joachim","7":"product_author-irlenkaeuser-jan-c","8":"product_cat-politik","9":"product_tag-bundeswehr","10":"product_tag-sicherheitspolitik","11":"product_tag-militaer","12":"pa_verlag-verlag-barbara-budrich","13":"wpbf-post","16":"instock","17":"taxable","18":"shipping-taxable","19":"purchasable","20":"product-type-variable","21":"has-default-attributes"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bundeswehr - Die n\u00e4chsten 50 Jahre<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/shop.budrich.de\/en\/product-2\/bundeswehr-die-naechsten-50-jahre\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bundeswehr - Die n\u00e4chsten 50 Jahre\" \/>\n<meta property=\"og:description\" content=\"Joachim Krause Jan C. Irlenk\u00e4user(Hrsg.) Bundeswehr - Die n\u00e4chsten 50 Jahre Anforderungen an deutsche Streitkr\u00e4fte im 21. Jahrhun\u00addert. 2006. 314 S. Kt. 36,00 \u0080 (D), 37,10 \u0080 (A)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/shop.budrich.de\/en\/product-2\/bundeswehr-die-naechsten-50-jahre\/\" \/>\n<meta property=\"og:site_name\" content=\"Verlag Barbara Budrich\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-26T12:10:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/shop.budrich.de\/wp-content\/uploads\/2015\/10\/97838664900621.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"494\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/bundeswehr-die-naechsten-50-jahre\\\/\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/bundeswehr-die-naechsten-50-jahre\\\/\",\"name\":\"Bundeswehr - Die n\u00e4chsten 50 Jahre\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/bundeswehr-die-naechsten-50-jahre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/bundeswehr-die-naechsten-50-jahre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/97838664900621.jpg\",\"datePublished\":\"2006-03-27T14:40:23+00:00\",\"dateModified\":\"2021-02-26T12:10:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/bundeswehr-die-naechsten-50-jahre\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/bundeswehr-die-naechsten-50-jahre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/bundeswehr-die-naechsten-50-jahre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/97838664900621.jpg\",\"contentUrl\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/97838664900621.jpg\",\"width\":494,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/bundeswehr-die-naechsten-50-jahre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/shop.budrich.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Programm\",\"item\":\"https:\\\/\\\/shop.budrich.de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bundeswehr &#8211; Die n\u00e4chsten 50 Jahre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#website\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/\",\"name\":\"Verlag Barbara Budrich\",\"description\":\"Qualitativ hochwertige Publikationen f\u00fcr die Sozial- und Erziehungswissenschaften\",\"publisher\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/shop.budrich.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#organization\",\"name\":\"Verlag Barbara Budrich GmbH\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/verlag-barbara-budrich-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/verlag-barbara-budrich-logo.jpg\",\"width\":354,\"height\":354,\"caption\":\"Verlag Barbara Budrich GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bundeswehr - Die n\u00e4chsten 50 Jahre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/shop.budrich.de\/en\/product-2\/bundeswehr-die-naechsten-50-jahre\/","og_locale":"en_US","og_type":"article","og_title":"Bundeswehr - Die n\u00e4chsten 50 Jahre","og_description":"Joachim Krause Jan C. Irlenk\u00e4user(Hrsg.) Bundeswehr - Die n\u00e4chsten 50 Jahre Anforderungen an deutsche Streitkr\u00e4fte im 21. Jahrhun\u00addert. 2006. 314 S. Kt. 36,00 \u0080 (D), 37,10 \u0080 (A)","og_url":"https:\/\/shop.budrich.de\/en\/product-2\/bundeswehr-die-naechsten-50-jahre\/","og_site_name":"Verlag Barbara Budrich","article_modified_time":"2021-02-26T12:10:09+00:00","og_image":[{"width":494,"height":700,"url":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2015\/10\/97838664900621.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/shop.budrich.de\/produkt\/bundeswehr-die-naechsten-50-jahre\/","url":"https:\/\/shop.budrich.de\/produkt\/bundeswehr-die-naechsten-50-jahre\/","name":"Bundeswehr - Die n\u00e4chsten 50 Jahre","isPartOf":{"@id":"https:\/\/shop.budrich.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/shop.budrich.de\/produkt\/bundeswehr-die-naechsten-50-jahre\/#primaryimage"},"image":{"@id":"https:\/\/shop.budrich.de\/produkt\/bundeswehr-die-naechsten-50-jahre\/#primaryimage"},"thumbnailUrl":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2015\/10\/97838664900621.jpg","datePublished":"2006-03-27T14:40:23+00:00","dateModified":"2021-02-26T12:10:09+00:00","breadcrumb":{"@id":"https:\/\/shop.budrich.de\/produkt\/bundeswehr-die-naechsten-50-jahre\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/shop.budrich.de\/produkt\/bundeswehr-die-naechsten-50-jahre\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/shop.budrich.de\/produkt\/bundeswehr-die-naechsten-50-jahre\/#primaryimage","url":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2015\/10\/97838664900621.jpg","contentUrl":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2015\/10\/97838664900621.jpg","width":494,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/shop.budrich.de\/produkt\/bundeswehr-die-naechsten-50-jahre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/shop.budrich.de\/"},{"@type":"ListItem","position":2,"name":"Programm","item":"https:\/\/shop.budrich.de\/shop\/"},{"@type":"ListItem","position":3,"name":"Bundeswehr &#8211; Die n\u00e4chsten 50 Jahre"}]},{"@type":"WebSite","@id":"https:\/\/shop.budrich.de\/#website","url":"https:\/\/shop.budrich.de\/","name":"Verlag Barbara Budrich","description":"Qualitativ hochwertige Publikationen f\u00fcr die Sozial- und Erziehungswissenschaften","publisher":{"@id":"https:\/\/shop.budrich.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/shop.budrich.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/shop.budrich.de\/#organization","name":"Verlag Barbara Budrich GmbH","url":"https:\/\/shop.budrich.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/shop.budrich.de\/#\/schema\/logo\/image\/","url":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2020\/11\/verlag-barbara-budrich-logo.jpg","contentUrl":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2020\/11\/verlag-barbara-budrich-logo.jpg","width":354,"height":354,"caption":"Verlag Barbara Budrich GmbH"},"image":{"@id":"https:\/\/shop.budrich.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product\/17485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/comments?post=17485"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/media\/19532"}],"wp:attachment":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/media?parent=17485"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product_brand?post=17485"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product_cat?post=17485"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product_tag?post=17485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}