{"id":189786,"date":"2025-09-01T03:00:02","date_gmt":"2025-09-01T01:00:02","guid":{"rendered":"https:\/\/shop.budrich.de\/?post_type=product&#038;p=189786"},"modified":"2025-12-18T10:37:51","modified_gmt":"2025-12-18T09:37:51","slug":"biographische-fundierungen-paedagogischer-professionalitaet","status":"publish","type":"product","link":"https:\/\/shop.budrich.de\/en\/produkt\/biographische-fundierungen-paedagogischer-professionalitaet\/","title":{"rendered":"Biographische Fundierungen p\u00e4dagogischer Professionalit\u00e4t"},"content":{"rendered":"<p><strong>Wie pr\u00e4gt die Biographie den Beruf als Politiklehrkraft? Und welche Verbindungen zwischen Biographie und Fachverst\u00e4ndnis bestehen bei Lehrkr\u00e4ften, die in einer historisch-politischen Ausnahmesituation aufgewachsen sind und in den 1960er Jahren erstmals das neue Fach Politikwissenschaft studiert haben? Der Autor fragt nach den biographischen Erfahrungen dieser ersten eigentlichen Politiklehrkr\u00e4fte, um deren Einfluss auf die Herausbildung professioneller Fachorientierungen rekonstruieren zu k\u00f6nnen.<\/strong><\/p>\n<p>Trotz wissenschaftlicher Hinweise auf die Erfahrungsgebundenheit professioneller Orientierungsmuster konzentriert sich die politikdidaktische Forschung bislang st\u00e4rker auf die Diagnose als auf die Genese des Professionswissens. Politiklehrkr\u00e4fte der ersten Generation sind daher kaum biographieanalytisch untersucht worden. Dabei er\u00f6ffnet gerade ihre generationsgeschichtliche Verortung sowie die r\u00fcckblickende Perspektive am Lebensabend wertvolle Einblicke in den Zusammenhang zwischen biographischen Erfahrungen und professionellen Orientierungsmustern. Die im Buch dargestellten Biographien verdeutlichen Verbindungen zwischen Lebensgeschichte, politischer Haltung und Vorstellungen politischer Bildung.<\/p>\n<p><strong>Der Autor:<\/strong><br \/>\n<b>Jascha Hook<\/b>, von 2018 bis 2025 wissenschaftlicher Mitarbeiter am Arbeitsbereich Historische Bildungsforschung an der Rheinland-Pf\u00e4lzischen Technischen Universit\u00e4t Kaiserslautern-Landau<\/p>\n<p><strong>Der Fachbereich:<\/strong><br \/>\nEducational Science<\/p>","protected":false},"excerpt":{"rendered":"<p>Wie pr\u00e4gt die Biographie den Beruf als Politiklehrkraft? Und welche Verbindungen zwischen Biographie und Fachverst\u00e4ndnis bestehen bei Lehrkr\u00e4ften, die in einer historisch-politischen Ausnahmesituation aufgewachsen sind und in den 1960er Jahren erstmals das neue Fach Politikwissenschaft studiert haben? Der Autor fragt nach den biographischen Erfahrungen dieser ersten eigentlichen Politiklehrkr\u00e4fte, um deren Einfluss auf die Herausbildung professioneller [&hellip;]<\/p>\n","protected":false},"featured_media":190195,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[23842,7609],"product_tag":[57437,44165,57538,50096,7624,7667,7700,57435,57436],"class_list":{"0":"post-189786","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_author-jascha-hook","7":"product_cat-fachbereiche","8":"product_cat-erziehung","9":"product_tag-politiklehrkraefte","10":"product_tag-professionswissen","11":"product_tag-september-2025","12":"product_tag-lehrerprofessionalitaet","13":"product_tag-politische-bildung","14":"product_tag-biographieforschung","15":"product_tag-biographie","16":"product_tag-lehrerforschung","17":"product_tag-sozialkunde","18":"pa_reihe-qualitative-fall-und-prozessanalysen-biographie-interaktion-soziale-welten","19":"pa_verlag-verlag-barbara-budrich","20":"wpbf-post","23":"instock","24":"taxable","25":"shipping-taxable","26":"purchasable","27":"product-type-variable","28":"has-default-attributes"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Biographische Fundierungen p\u00e4dagogischer Professionalit\u00e4t<\/title>\n<meta name=\"description\" content=\"Hook, Eine qualitative Studie zur Herausbildung der professionellen Orientierungen von Politiklehrkr\u00e4ften der Jahrg\u00e4nge 1935 bis 1945.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/shop.budrich.de\/en\/product-2\/biographische-fundierungen-paedagogischer-professionalitaet\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Biographische Fundierungen p\u00e4dagogischer Professionalit\u00e4t\" \/>\n<meta property=\"og:description\" content=\"Hook, Eine qualitative Studie zur Herausbildung der professionellen Orientierungen von Politiklehrkr\u00e4ften der Jahrg\u00e4nge 1935 bis 1945.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/shop.budrich.de\/en\/product-2\/biographische-fundierungen-paedagogischer-professionalitaet\/\" \/>\n<meta property=\"og:site_name\" content=\"Verlag Barbara Budrich\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-18T09:37:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/shop.budrich.de\/wp-content\/uploads\/2025\/08\/9783847431749-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1442\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/biographische-fundierungen-paedagogischer-professionalitaet\\\/\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/biographische-fundierungen-paedagogischer-professionalitaet\\\/\",\"name\":\"Biographische Fundierungen p\u00e4dagogischer Professionalit\u00e4t\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/biographische-fundierungen-paedagogischer-professionalitaet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/biographische-fundierungen-paedagogischer-professionalitaet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/9783847431749-scaled.jpg\",\"datePublished\":\"2025-09-01T01:00:02+00:00\",\"dateModified\":\"2025-12-18T09:37:51+00:00\",\"description\":\"Hook, Eine qualitative Studie zur Herausbildung der professionellen Orientierungen von Politiklehrkr\u00e4ften der Jahrg\u00e4nge 1935 bis 1945.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/biographische-fundierungen-paedagogischer-professionalitaet\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/biographische-fundierungen-paedagogischer-professionalitaet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/biographische-fundierungen-paedagogischer-professionalitaet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/9783847431749-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/9783847431749-scaled.jpg\",\"width\":1442,\"height\":2048,\"caption\":\"Cover: Biographische Fundierungen p\u00e4dagogischer Professionalit\u00e4t\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/biographische-fundierungen-paedagogischer-professionalitaet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/shop.budrich.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Programm\",\"item\":\"https:\\\/\\\/shop.budrich.de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Biographische Fundierungen p\u00e4dagogischer Professionalit\u00e4t\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#website\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/\",\"name\":\"Verlag Barbara Budrich\",\"description\":\"Qualitativ hochwertige Publikationen f\u00fcr die Sozial- und Erziehungswissenschaften\",\"publisher\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/shop.budrich.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#organization\",\"name\":\"Verlag Barbara Budrich GmbH\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/verlag-barbara-budrich-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/verlag-barbara-budrich-logo.jpg\",\"width\":354,\"height\":354,\"caption\":\"Verlag Barbara Budrich GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Biographische Fundierungen p\u00e4dagogischer Professionalit\u00e4t","description":"Hook, Eine qualitative Studie zur Herausbildung der professionellen Orientierungen von Politiklehrkr\u00e4ften der Jahrg\u00e4nge 1935 bis 1945.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/shop.budrich.de\/en\/product-2\/biographische-fundierungen-paedagogischer-professionalitaet\/","og_locale":"en_US","og_type":"article","og_title":"Biographische Fundierungen p\u00e4dagogischer Professionalit\u00e4t","og_description":"Hook, Eine qualitative Studie zur Herausbildung der professionellen Orientierungen von Politiklehrkr\u00e4ften der Jahrg\u00e4nge 1935 bis 1945.","og_url":"https:\/\/shop.budrich.de\/en\/product-2\/biographische-fundierungen-paedagogischer-professionalitaet\/","og_site_name":"Verlag Barbara Budrich","article_modified_time":"2025-12-18T09:37:51+00:00","og_image":[{"width":1442,"height":2048,"url":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2025\/08\/9783847431749-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/shop.budrich.de\/produkt\/biographische-fundierungen-paedagogischer-professionalitaet\/","url":"https:\/\/shop.budrich.de\/produkt\/biographische-fundierungen-paedagogischer-professionalitaet\/","name":"Biographische Fundierungen p\u00e4dagogischer Professionalit\u00e4t","isPartOf":{"@id":"https:\/\/shop.budrich.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/shop.budrich.de\/produkt\/biographische-fundierungen-paedagogischer-professionalitaet\/#primaryimage"},"image":{"@id":"https:\/\/shop.budrich.de\/produkt\/biographische-fundierungen-paedagogischer-professionalitaet\/#primaryimage"},"thumbnailUrl":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2025\/08\/9783847431749-scaled.jpg","datePublished":"2025-09-01T01:00:02+00:00","dateModified":"2025-12-18T09:37:51+00:00","description":"Hook, Eine qualitative Studie zur Herausbildung der professionellen Orientierungen von Politiklehrkr\u00e4ften der Jahrg\u00e4nge 1935 bis 1945.","breadcrumb":{"@id":"https:\/\/shop.budrich.de\/produkt\/biographische-fundierungen-paedagogischer-professionalitaet\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/shop.budrich.de\/produkt\/biographische-fundierungen-paedagogischer-professionalitaet\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/shop.budrich.de\/produkt\/biographische-fundierungen-paedagogischer-professionalitaet\/#primaryimage","url":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2025\/08\/9783847431749-scaled.jpg","contentUrl":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2025\/08\/9783847431749-scaled.jpg","width":1442,"height":2048,"caption":"Cover: Biographische Fundierungen p\u00e4dagogischer Professionalit\u00e4t"},{"@type":"BreadcrumbList","@id":"https:\/\/shop.budrich.de\/produkt\/biographische-fundierungen-paedagogischer-professionalitaet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/shop.budrich.de\/"},{"@type":"ListItem","position":2,"name":"Programm","item":"https:\/\/shop.budrich.de\/shop\/"},{"@type":"ListItem","position":3,"name":"Biographische Fundierungen p\u00e4dagogischer Professionalit\u00e4t"}]},{"@type":"WebSite","@id":"https:\/\/shop.budrich.de\/#website","url":"https:\/\/shop.budrich.de\/","name":"Verlag Barbara Budrich","description":"Qualitativ hochwertige Publikationen f\u00fcr die Sozial- und Erziehungswissenschaften","publisher":{"@id":"https:\/\/shop.budrich.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/shop.budrich.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/shop.budrich.de\/#organization","name":"Verlag Barbara Budrich GmbH","url":"https:\/\/shop.budrich.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/shop.budrich.de\/#\/schema\/logo\/image\/","url":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2020\/11\/verlag-barbara-budrich-logo.jpg","contentUrl":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2020\/11\/verlag-barbara-budrich-logo.jpg","width":354,"height":354,"caption":"Verlag Barbara Budrich GmbH"},"image":{"@id":"https:\/\/shop.budrich.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product\/189786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/comments?post=189786"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/media\/190195"}],"wp:attachment":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/media?parent=189786"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product_brand?post=189786"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product_cat?post=189786"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product_tag?post=189786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}