{"id":211673,"date":"2026-07-15T08:00:28","date_gmt":"2026-07-15T06:00:28","guid":{"rendered":"https:\/\/shop.budrich.de\/?post_type=product&#038;p=211673"},"modified":"2026-07-15T09:26:00","modified_gmt":"2026-07-15T07:26:00","slug":"politisches-lernen-12-2026-politische-bildung-nachhaltige-entwicklung","status":"publish","type":"product","link":"https:\/\/shop.budrich.de\/en\/produkt\/politisches-lernen-12-2026-politische-bildung-nachhaltige-entwicklung\/","title":{"rendered":"Politisches Lernen 1+2-2026 | Politische Bildung f\u00fcr nachhaltige Entwicklung"},"content":{"rendered":"<p><strong>Politisches Lernen<br \/>\n1+2-2026: Politische Bildung f\u00fcr nachhaltige Entwicklung<\/strong><\/p>\n<p><em>Themenschwerpunkt<\/em><br \/>\n<strong>Florian D\u00fcck \/ Harald Hantke \/ Stella Heitzhausen \/ Marvin L\u00fcters \/ Lorena Murawski \/ Bettina Zurstrassen:<\/strong> Politische Bildung f\u00fcr nachhaltige Entwicklung \u2013 in der beruflichen Ausbildung in Betrieb, Schule und lernort\u00fcbergreifend<br \/>\n<strong>Katharina Schmidt \/ Yannik Achenbach:<\/strong> Potenziale von Bildung f\u00fcr nachhaltige Entwicklung f\u00fcr eine inklusive politische Bildung f\u00fcr Sch\u00fcler:innen mit Lern- und Entwicklungsst\u00f6rungen<br \/>\n<strong>Michael B\u00f6cher \/ Juliana Hilf:<\/strong> Zwischen Seminarraum, Politik und Zivilgesellschaft: Service Learning als Erfahrungsraum politischer Bildung f\u00fcr nachhaltige Entwicklung<br \/>\n<strong>Katharina Hiller:<\/strong> Regionale Lernendenvorstellungen und Transformation: Forschendes Lernen zur Mobilit\u00e4tswende<br \/>\n<strong>Bettina Zurstrassen:<\/strong> Wohin geht die Weltkultur? \u2013 Konsequenzen f\u00fcr die Politische Bildung. Ein Interview* mit <strong>Roland Benedikter<\/strong> \u00fcber die Ergebnisse der UNESCO MONDIACULT-Konferenz 2025<\/p>\n<p><em>Diskussion<\/em><br \/>\n<strong>Daniel te Vrugt \/ Karin Meendermann:<\/strong> \u201eMit den Augen eines Avatars\u201c \u2013 Telepr\u00e4senzroboter als Br\u00fccke zur aktiven Teilhabe in Schule und Unterricht<\/p>\n<p><em>Fachdidaktische Werkstatt<\/em><br \/>\n<strong>Juliana F\u00f6rster:<\/strong> Diskursive Didaktik zur St\u00e4rkung politischer Urteils- und Handlungsf\u00e4higkeit in der Bildung f\u00fcr nachhaltige Entwicklung<br \/>\n<strong>Nele Mai:<\/strong> K\u00fcnstliche Intelligenz und Nachhaltigkeit als Gegenstand partizipativer Bildungsprozesse: Ein Praxisbeispiel<br \/>\n<strong>Jonas Schmidt \/ Katharina R\u00f6ll-Berge:<\/strong> Nachhaltige Ern\u00e4hrung im Politikunterricht fokussieren \u2013 Handlungsorientierte Unterrichtsmodule zur F\u00f6rderung der Selbstwirksamkeit und politischer Gestaltungskompetenz<br \/>\n<strong>Viviane Frank \/ Andreas Schal\u00fcck:<\/strong> Supply chain of a bar of chocolate: (un)fair?! \u2013 Free trade and its impact on local workers. Ein Mystery f\u00fcr den bilingualen Wirtschaft-Politik-Unterricht in Klasse \/ Stufe 8<br \/>\n<strong>Gesine Bade:<\/strong> Politische Nachhaltigkeitsbildung in der Grundschule: das Planspiel \u201eTesla baut in Gr\u00fcnheide\u201c<br \/>\n<strong>Ann-Katrin Voit:<\/strong> Digitale Nachhaltigkeit als Politische Bildung f\u00fcr nachhaltige Entwicklung: Algorithmische Macht, Konsum und Demokratie in der beruflichen Bildung<\/p>\n<p><em>DVPB NW aktuell<\/em><br \/>\nLebensweltbezug st\u00e4rken, Wissenschaftlichkeit sichern, Interdisziplinarit\u00e4t f\u00f6rdern. Stellungnahme der DVPB NW zum Kernlehrplanentwurf. Sozialwissenschaften und Sozialwissenschaften \/ Wirtschaft der gymnasialen Oberstufe an Gymnasien und Gesamtschulen<br \/>\n<strong>Christel Schrieverhoff \/ Antje Menn:<\/strong> Der \u201eAbiturpreis Sozialwissenschaften der DVPB NW\u201c als Beitrag zur Demokratiebildung<br \/>\n<strong>Thorsten Obel \/ Christel Schrieverhoff:<\/strong> 25 Jahre \u201eJugend debattiert\u201c \u2013 lebendige faire Streitkultur beim Landesfinale Nordrhein-Westfalen<br \/>\nSchule zeigt Haltung<\/p>\n<p><em>Rezensionen<\/em><br \/>\nRezensierte B\u00fccher<br \/>\nAutorinnen und Autoren<br \/>\n<strong>Hans-Joachim von Olberg:<\/strong> Eine gelungene Neuinterpretation der Geschichte der politischen Bildung (Tim Schanetzky (2025): Politik der politischen Bildung. Das Ringen um die Demokratisierung der Deutschen seit 1945)<br \/>\n<strong>Christoph Ehmann:<\/strong> Bestrafungsfreies Stehlen und Morden (Tatjana T\u00f6nsmeyer (2014): Unter Deutscher Besatzung. Europa 1939\u20131945)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Einzelbeitrag-Download<\/strong> (Open Access\/Geb\u00fchr): <a href=\"https:\/\/pl.budrich-journals.de\" target=\"_blank\" rel=\"noopener noreferrer\">pl.budrich-journals.de<\/a><br \/>\nSie k\u00f6nnen sich <a href=\"https:\/\/alert-pl.budrich.de\" target=\"_blank\" rel=\"noopener\">hier<\/a> f\u00fcr den <strong>PL-Alert<\/strong> anmelden.<\/p>","protected":false},"excerpt":{"rendered":"<p>Politisches Lernen 1+2-2026: Politische Bildung f\u00fcr nachhaltige Entwicklung Themenschwerpunkt Florian D\u00fcck \/ Harald Hantke \/ Stella Heitzhausen \/ Marvin L\u00fcters \/ Lorena Murawski \/ Bettina Zurstrassen: Politische Bildung f\u00fcr nachhaltige Entwicklung \u2013 in der beruflichen Ausbildung in Betrieb, Schule und lernort\u00fcbergreifend Katharina Schmidt \/ Yannik Achenbach: Potenziale von Bildung f\u00fcr nachhaltige Entwicklung f\u00fcr eine inklusive [&hellip;]<\/p>\n","protected":false},"featured_media":211676,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[13145,20881,20882],"product_tag":[59755,7624,59756,7664,39140,59757,59758,39664,59759,59760,41692,59750,53828,59761,26818,59751,54308,27338,59752,59763,32542,59753,59572,32992,59754],"class_list":{"0":"post-211673","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_author-florian-dueck","7":"product_author-harald-hantke","8":"product_author-stella-heitzhausen","9":"product_author-marvin-lueters","10":"product_author-lorena-murawski","11":"product_author-bettina-zurstrassen","12":"product_author-katharina-schmidt","13":"product_author-yannik-achenbach","14":"product_author-michael-boecher","15":"product_author-juliana-hilf","16":"product_author-katharina-hiller","17":"product_author-daniel-te-vrugt","18":"product_author-karin-meendermann","19":"product_author-juliana-foerster","20":"product_author-nele-mai","21":"product_author-jonas-schmidt","22":"product_author-katharina-roell-berge","23":"product_author-viviane-frank","24":"product_author-andreas-schalueck","25":"product_author-gesine-bade","26":"product_author-ann-katrin-voit","27":"product_author-christel-schrieverhoff","28":"product_author-antje-menn","29":"product_author-thorsten-obel","30":"product_author-hans-joachim-von-olberg","31":"product_author-christoph-ehmann","32":"product_author-roland-benedikter","33":"product_cat-einzelhefte","34":"product_cat-neuerscheinungen","35":"product_cat-neuerscheinungen-im-newsletter","36":"product_tag-partizipative-bildungsprozesse","37":"product_tag-politische-bildung","38":"product_tag-handlungsorientierte-unterrichtsmodule","39":"product_tag-grundschule","40":"product_tag-kuenstliche-intelligenz","41":"product_tag-politische-gestaltungskompetenz","42":"product_tag-free-trade","43":"product_tag-nachhaltige-ernaehrung","44":"product_tag-politische-nachhaltigkeitsbildung","45":"product_tag-abiturpreis-sozialwissenschaften-der-dvpb-nw","46":"product_tag-selbstwirksamkeit","47":"product_tag-inklusive-politische-bildung","48":"product_tag-aktive-teilhabe","49":"product_tag-jugend-debattiert","50":"product_tag-nachhaltige-entwicklung","51":"product_tag-lern-und-entwicklungsstoerungen","52":"product_tag-telepraesenzroboter","53":"product_tag-berufliche-ausbildung","54":"product_tag-mobilitaetswende","55":"product_tag-bilingualer-wirtschaft-politik-unterricht","56":"product_tag-service-learning","57":"product_tag-unesco-mondiacult-konferenz-2025","58":"product_tag-juli-2026","59":"product_tag-demokratiebildung","60":"product_tag-diskursive-didaktik","61":"pa_verlag-verlag-barbara-budrich","62":"wpbf-post","65":"instock","66":"taxable","67":"shipping-taxable","68":"purchasable","69":"product-type-variable","70":"has-default-attributes"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Politisches Lernen 1+2-2026 | Politische Bildung f\u00fcr nachhaltige Entwicklung<\/title>\n<meta name=\"description\" content=\"ISSN 0937-2946 | eISSN 2750-1965 | 44. Jg. 2026 | Juli 2026 | 72 Seiten | Verlag Barbara Budrich | Wissenschaftliche Fachzeitschrift\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/shop.budrich.de\/en\/product-2\/politisches-lernen-12-2026-politische-bildung-nachhaltige-entwicklung\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Politisches Lernen 1+2-2026 | Politische Bildung f\u00fcr nachhaltige Entwicklung\" \/>\n<meta property=\"og:description\" content=\"ISSN 0937-2946 | eISSN 2750-1965 | 44. Jg. 2026 | Juli 2026 | 72 Seiten | Verlag Barbara Budrich | Wissenschaftliche Fachzeitschrift\" \/>\n<meta property=\"og:url\" content=\"https:\/\/shop.budrich.de\/en\/product-2\/politisches-lernen-12-2026-politische-bildung-nachhaltige-entwicklung\/\" \/>\n<meta property=\"og:site_name\" content=\"Verlag Barbara Budrich\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T07:26:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/shop.budrich.de\/wp-content\/uploads\/2026\/06\/0937-2946-2026-12-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1442\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/politisches-lernen-12-2026-politische-bildung-nachhaltige-entwicklung\\\/\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/politisches-lernen-12-2026-politische-bildung-nachhaltige-entwicklung\\\/\",\"name\":\"Politisches Lernen 1+2-2026 | Politische Bildung f\u00fcr nachhaltige Entwicklung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/politisches-lernen-12-2026-politische-bildung-nachhaltige-entwicklung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/politisches-lernen-12-2026-politische-bildung-nachhaltige-entwicklung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/0937-2946-2026-12-scaled.jpg\",\"datePublished\":\"2026-07-15T06:00:28+00:00\",\"dateModified\":\"2026-07-15T07:26:00+00:00\",\"description\":\"ISSN 0937-2946 | eISSN 2750-1965 | 44. Jg. 2026 | Juli 2026 | 72 Seiten | Verlag Barbara Budrich | Wissenschaftliche Fachzeitschrift\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/politisches-lernen-12-2026-politische-bildung-nachhaltige-entwicklung\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/politisches-lernen-12-2026-politische-bildung-nachhaltige-entwicklung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/politisches-lernen-12-2026-politische-bildung-nachhaltige-entwicklung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/0937-2946-2026-12-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/0937-2946-2026-12-scaled.jpg\",\"width\":1442,\"height\":2048,\"caption\":\"Politisches Lernen 1+2-2026: Politische Bildung f\u00fcr nachhaltige Entwicklung\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/politisches-lernen-12-2026-politische-bildung-nachhaltige-entwicklung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/shop.budrich.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Programm\",\"item\":\"https:\\\/\\\/shop.budrich.de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Politisches Lernen 1+2-2026 | Politische Bildung f\u00fcr nachhaltige Entwicklung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#website\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/\",\"name\":\"Verlag Barbara Budrich\",\"description\":\"Qualitativ hochwertige Publikationen f\u00fcr die Sozial- und Erziehungswissenschaften\",\"publisher\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/shop.budrich.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#organization\",\"name\":\"Verlag Barbara Budrich GmbH\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/verlag-barbara-budrich-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/verlag-barbara-budrich-logo.jpg\",\"width\":354,\"height\":354,\"caption\":\"Verlag Barbara Budrich GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Politisches Lernen 1+2-2026 | Politische Bildung f\u00fcr nachhaltige Entwicklung","description":"ISSN 0937-2946 | eISSN 2750-1965 | 44. Jg. 2026 | Juli 2026 | 72 Seiten | Verlag Barbara Budrich | Wissenschaftliche Fachzeitschrift","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/shop.budrich.de\/en\/product-2\/politisches-lernen-12-2026-politische-bildung-nachhaltige-entwicklung\/","og_locale":"en_US","og_type":"article","og_title":"Politisches Lernen 1+2-2026 | Politische Bildung f\u00fcr nachhaltige Entwicklung","og_description":"ISSN 0937-2946 | eISSN 2750-1965 | 44. Jg. 2026 | Juli 2026 | 72 Seiten | Verlag Barbara Budrich | Wissenschaftliche Fachzeitschrift","og_url":"https:\/\/shop.budrich.de\/en\/product-2\/politisches-lernen-12-2026-politische-bildung-nachhaltige-entwicklung\/","og_site_name":"Verlag Barbara Budrich","article_modified_time":"2026-07-15T07:26:00+00:00","og_image":[{"width":1442,"height":2048,"url":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2026\/06\/0937-2946-2026-12-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/shop.budrich.de\/produkt\/politisches-lernen-12-2026-politische-bildung-nachhaltige-entwicklung\/","url":"https:\/\/shop.budrich.de\/produkt\/politisches-lernen-12-2026-politische-bildung-nachhaltige-entwicklung\/","name":"Politisches Lernen 1+2-2026 | Politische Bildung f\u00fcr nachhaltige Entwicklung","isPartOf":{"@id":"https:\/\/shop.budrich.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/shop.budrich.de\/produkt\/politisches-lernen-12-2026-politische-bildung-nachhaltige-entwicklung\/#primaryimage"},"image":{"@id":"https:\/\/shop.budrich.de\/produkt\/politisches-lernen-12-2026-politische-bildung-nachhaltige-entwicklung\/#primaryimage"},"thumbnailUrl":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2026\/06\/0937-2946-2026-12-scaled.jpg","datePublished":"2026-07-15T06:00:28+00:00","dateModified":"2026-07-15T07:26:00+00:00","description":"ISSN 0937-2946 | eISSN 2750-1965 | 44. Jg. 2026 | Juli 2026 | 72 Seiten | Verlag Barbara Budrich | Wissenschaftliche Fachzeitschrift","breadcrumb":{"@id":"https:\/\/shop.budrich.de\/produkt\/politisches-lernen-12-2026-politische-bildung-nachhaltige-entwicklung\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/shop.budrich.de\/produkt\/politisches-lernen-12-2026-politische-bildung-nachhaltige-entwicklung\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/shop.budrich.de\/produkt\/politisches-lernen-12-2026-politische-bildung-nachhaltige-entwicklung\/#primaryimage","url":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2026\/06\/0937-2946-2026-12-scaled.jpg","contentUrl":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2026\/06\/0937-2946-2026-12-scaled.jpg","width":1442,"height":2048,"caption":"Politisches Lernen 1+2-2026: Politische Bildung f\u00fcr nachhaltige Entwicklung"},{"@type":"BreadcrumbList","@id":"https:\/\/shop.budrich.de\/produkt\/politisches-lernen-12-2026-politische-bildung-nachhaltige-entwicklung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/shop.budrich.de\/"},{"@type":"ListItem","position":2,"name":"Programm","item":"https:\/\/shop.budrich.de\/shop\/"},{"@type":"ListItem","position":3,"name":"Politisches Lernen 1+2-2026 | Politische Bildung f\u00fcr nachhaltige Entwicklung"}]},{"@type":"WebSite","@id":"https:\/\/shop.budrich.de\/#website","url":"https:\/\/shop.budrich.de\/","name":"Verlag Barbara Budrich","description":"Qualitativ hochwertige Publikationen f\u00fcr die Sozial- und Erziehungswissenschaften","publisher":{"@id":"https:\/\/shop.budrich.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/shop.budrich.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/shop.budrich.de\/#organization","name":"Verlag Barbara Budrich GmbH","url":"https:\/\/shop.budrich.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/shop.budrich.de\/#\/schema\/logo\/image\/","url":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2020\/11\/verlag-barbara-budrich-logo.jpg","contentUrl":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2020\/11\/verlag-barbara-budrich-logo.jpg","width":354,"height":354,"caption":"Verlag Barbara Budrich GmbH"},"image":{"@id":"https:\/\/shop.budrich.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product\/211673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/comments?post=211673"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/media\/211676"}],"wp:attachment":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/media?parent=211673"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product_brand?post=211673"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product_cat?post=211673"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product_tag?post=211673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}