{"id":44903,"date":"2017-04-03T15:40:00","date_gmt":"2017-04-03T14:40:05","guid":{"rendered":"https:\/\/shop.budrich-academic.de\/produkt\/sprache-im-italienischen-erdkundeunterricht\/"},"modified":"2021-03-29T15:59:07","modified_gmt":"2021-03-29T13:59:07","slug":"sprache-im-italienischen-erdkundeunterricht","status":"publish","type":"product","link":"https:\/\/shop.budrich.de\/en\/produkt\/sprache-im-italienischen-erdkundeunterricht\/","title":{"rendered":"Sprache im italienischen Erdkundeunterricht"},"content":{"rendered":"<p><em><strong>Open Access: <\/strong><\/em><em>Dieser Titel ist <a href=\"https:\/\/shop.budrich.de\/wp-content\/uploads\/2016\/11\/9783863883034.pdf\" target=\"_blank\" rel=\"noopener\" data-wpel-link=\"internal\">kostenlos im Open Access herunterladbar (PDF)<\/a> oder kostenpflichtig als Print-Ausgabe erh\u00e4ltlich.<\/em><\/p>\n<p><strong><span style=\"color: #0000ff;\"><br \/>\n<\/span> <\/strong><\/p>\n<p><strong>Die Autorin untersucht sprachliche Herausforderungen, denen Lernende am Ende der Sekundarstufe I im Fachunterricht begegnen. Ihre empirischen Daten stammen aus Schulen in Italien. Zwischen dem Sprachgebrauch der Lernenden und den in den Schulb\u00fcchern und von Lehrkr\u00e4ften verwendeten Registern stellt sie Diskrepanzen fest. Im Zentrum der Analysen steht der Wortschatz, und es werden weitere sprachliche Aspekte und die Rolle der Fachlehrkr\u00e4fte f\u00fcr sprachliche Bildung erforscht.<\/strong><\/p>\n<p>Bildungssprachliche F\u00e4higkeiten sind f\u00fcr den Schulerfolg und eine aktive Teilhabe am gesellschaftlichen Leben wichtig. Dass ein Teil der Lernenden \u00fcber diese F\u00e4higkeiten nur eingeschr\u00e4nkt verf\u00fcgt, haben gro\u00dfangelegte Schulleistungsstudien gezeigt. Vor allem Sch\u00fclerinnen und Sch\u00fclern, deren Erstsprache nicht die Unterrichtssprache ist, stehen hier vor gro\u00dfen Herausforderungen. Schwierigkeiten resultieren dabei nicht nur aus der Verwendung spezifischer Fachwortsch\u00e4tze, sondern betreffen den Sprachgebrauch weitreichender. Doch wo liegen die H\u00fcrden im Einzelnen? Mit einer qualitativen Studie geht die Autorin dieser Frage auf den Grund, indem sie aus verschiedenen Blickwinkeln die sprachlichen Herausforderungen f\u00fcr Lernende betrachtet und Beobachtungen dazu anstellt, wie sich Lehrkr\u00e4fte und Lernende diesen Herausforderungen stellen. Beleuchtet wird der Erdkundeunterricht mehrerer achter Klassen an drei Schulen Roms. In diesem Unterricht kommt dem Lehrbuch eine wichtige Funktion zu. Die sprachliche Gestaltung der Lehrwerke \u00fcbersteigt die F\u00e4higkeiten der Lernenden in vielen F\u00e4llen. Die Lehrenden m\u00fcssen daher eine Br\u00fcckenfunktion \u00fcbernehmen. Die Untersuchung ist f\u00fcr Studierende, Forschende, Lehrende und LehrbuchautorInnen \u00fcber die italienischen Landesgrenzen hinaus aufschlussreich, da viele der angesprochenen Ph\u00e4nomene unabh\u00e4ngig von ihrer einzelsprachlichen Konkretisierung auftreten. Die Studie gibt mit einem multiperspektivischen Ansatz einen Einblick in das komplexe Ph\u00e4nomen des schulischen Sprachgebrauchs und der Sprachbildung. Die Ergebnisse fu\u00dfen auf Unterrichtsbeobachtungen und Gespr\u00e4chsanalysen, auf Sprachtests, die anhand von im Unterricht behandelten Lehrbuchtexten konstruiert sind (C-Tests), auf einer detaillierten sprachlichen Analyse verschiedener Lehrwerke, auf einem Sch\u00fclerfragebogen zu relevanten Faktoren sowie der Auswertung diverser Textproduktionen der Lernenden.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/shop.budrich.de\/wp-content\/uploads\/2016\/11\/9783863887438_iv.pdf\">Inhaltsverzeichnis ansehen<\/a><br \/>\n<strong>Die Autorin:<\/strong><br \/>\n<strong>Stephanie Sch\u00f6ber, PhD,<\/strong><br \/>\nDeutschlehrerin in Rom, Italien<\/p>\n<p>&nbsp;<\/p>\n<p>Hier finden Sie den <a href=\"https:\/\/shop.budrich.de\/wp-content\/uploads\/2016\/11\/743-sch\u00f6ber.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Waschzettel<\/a> zum Buch (pdf- Infoblatt).<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Zielgruppen:<\/strong><br \/>\nStudierende, Forschende und Lehrende der Sprach-, Erziehungs- und Bildungswissenschaften sowie SchulbuchautorInnen<\/p>","protected":false},"excerpt":{"rendered":"<p>Open Access: Dieser Titel ist kostenlos im Open Access herunterladbar (PDF) oder kostenpflichtig als Print-Ausgabe erh\u00e4ltlich. Die Autorin untersucht sprachliche Herausforderungen, denen Lernende am Ende der Sekundarstufe I im Fachunterricht begegnen. Ihre empirischen Daten stammen aus Schulen in Italien. Zwischen dem Sprachgebrauch der Lernenden und den in den Schulb\u00fcchern und von Lehrkr\u00e4ften verwendeten Registern stellt [&hellip;]<\/p>\n","protected":false},"featured_media":47217,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[7609,12497],"product_tag":[19880,19881,19882],"class_list":{"0":"post-44903","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_author-stephanie-schoeber","7":"product_cat-erziehung","8":"product_cat-open-access","9":"product_tag-schulische-sprachbildung","10":"product_tag-unterricht-in-italien","11":"product_tag-fachunterricht-geographie","12":"pa_verlag-budrich-unipress","13":"wpbf-post","16":"instock","17":"taxable","18":"shipping-taxable","19":"purchasable","20":"product-type-variable"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sprache im italienischen Erdkundeunterricht<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/shop.budrich.de\/en\/product-2\/sprache-im-italienischen-erdkundeunterricht\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sprache im italienischen Erdkundeunterricht\" \/>\n<meta property=\"og:description\" content=\"Open Access: Dieser Titel ist kostenlos im Open Access herunterladbar (PDF) oder kostenpflichtig als Print-Ausgabe erh\u00e4ltlich. Die Autorin untersucht sprachliche Herausforderungen, denen Lernende am Ende der Sekundarstufe I im Fachunterricht begegnen. Ihre empirischen Daten stammen aus Schulen in Italien. Zwischen dem Sprachgebrauch der Lernenden und den in den Schulb\u00fcchern und von Lehrkr\u00e4ften verwendeten Registern stellt [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/shop.budrich.de\/en\/product-2\/sprache-im-italienischen-erdkundeunterricht\/\" \/>\n<meta property=\"og:site_name\" content=\"Verlag Barbara Budrich\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-29T13:59:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/shop.budrich.de\/wp-content\/uploads\/2016\/11\/9783863887438-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"458\" \/>\n\t<meta property=\"og:image:height\" content=\"648\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/sprache-im-italienischen-erdkundeunterricht\\\/\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/sprache-im-italienischen-erdkundeunterricht\\\/\",\"name\":\"Sprache im italienischen Erdkundeunterricht\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/sprache-im-italienischen-erdkundeunterricht\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/sprache-im-italienischen-erdkundeunterricht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/9783863887438-1.jpg\",\"datePublished\":\"2017-04-03T14:40:05+00:00\",\"dateModified\":\"2021-03-29T13:59:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/sprache-im-italienischen-erdkundeunterricht\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/sprache-im-italienischen-erdkundeunterricht\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/sprache-im-italienischen-erdkundeunterricht\\\/#primaryimage\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/9783863887438-1.jpg\",\"contentUrl\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/9783863887438-1.jpg\",\"width\":458,\"height\":648},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/sprache-im-italienischen-erdkundeunterricht\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/shop.budrich.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Programm\",\"item\":\"https:\\\/\\\/shop.budrich.de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sprache im italienischen Erdkundeunterricht\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#website\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/\",\"name\":\"Verlag Barbara Budrich\",\"description\":\"Qualitativ hochwertige Publikationen f\u00fcr die Sozial- und Erziehungswissenschaften\",\"publisher\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/shop.budrich.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#organization\",\"name\":\"Verlag Barbara Budrich GmbH\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/verlag-barbara-budrich-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/verlag-barbara-budrich-logo.jpg\",\"width\":354,\"height\":354,\"caption\":\"Verlag Barbara Budrich GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sprache im italienischen Erdkundeunterricht","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/shop.budrich.de\/en\/product-2\/sprache-im-italienischen-erdkundeunterricht\/","og_locale":"en_US","og_type":"article","og_title":"Sprache im italienischen Erdkundeunterricht","og_description":"Open Access: Dieser Titel ist kostenlos im Open Access herunterladbar (PDF) oder kostenpflichtig als Print-Ausgabe erh\u00e4ltlich. Die Autorin untersucht sprachliche Herausforderungen, denen Lernende am Ende der Sekundarstufe I im Fachunterricht begegnen. Ihre empirischen Daten stammen aus Schulen in Italien. Zwischen dem Sprachgebrauch der Lernenden und den in den Schulb\u00fcchern und von Lehrkr\u00e4ften verwendeten Registern stellt [&hellip;]","og_url":"https:\/\/shop.budrich.de\/en\/product-2\/sprache-im-italienischen-erdkundeunterricht\/","og_site_name":"Verlag Barbara Budrich","article_modified_time":"2021-03-29T13:59:07+00:00","og_image":[{"width":458,"height":648,"url":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2016\/11\/9783863887438-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/shop.budrich.de\/produkt\/sprache-im-italienischen-erdkundeunterricht\/","url":"https:\/\/shop.budrich.de\/produkt\/sprache-im-italienischen-erdkundeunterricht\/","name":"Sprache im italienischen Erdkundeunterricht","isPartOf":{"@id":"https:\/\/shop.budrich.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/shop.budrich.de\/produkt\/sprache-im-italienischen-erdkundeunterricht\/#primaryimage"},"image":{"@id":"https:\/\/shop.budrich.de\/produkt\/sprache-im-italienischen-erdkundeunterricht\/#primaryimage"},"thumbnailUrl":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2016\/11\/9783863887438-1.jpg","datePublished":"2017-04-03T14:40:05+00:00","dateModified":"2021-03-29T13:59:07+00:00","breadcrumb":{"@id":"https:\/\/shop.budrich.de\/produkt\/sprache-im-italienischen-erdkundeunterricht\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/shop.budrich.de\/produkt\/sprache-im-italienischen-erdkundeunterricht\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/shop.budrich.de\/produkt\/sprache-im-italienischen-erdkundeunterricht\/#primaryimage","url":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2016\/11\/9783863887438-1.jpg","contentUrl":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2016\/11\/9783863887438-1.jpg","width":458,"height":648},{"@type":"BreadcrumbList","@id":"https:\/\/shop.budrich.de\/produkt\/sprache-im-italienischen-erdkundeunterricht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/shop.budrich.de\/"},{"@type":"ListItem","position":2,"name":"Programm","item":"https:\/\/shop.budrich.de\/shop\/"},{"@type":"ListItem","position":3,"name":"Sprache im italienischen Erdkundeunterricht"}]},{"@type":"WebSite","@id":"https:\/\/shop.budrich.de\/#website","url":"https:\/\/shop.budrich.de\/","name":"Verlag Barbara Budrich","description":"Qualitativ hochwertige Publikationen f\u00fcr die Sozial- und Erziehungswissenschaften","publisher":{"@id":"https:\/\/shop.budrich.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/shop.budrich.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/shop.budrich.de\/#organization","name":"Verlag Barbara Budrich GmbH","url":"https:\/\/shop.budrich.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/shop.budrich.de\/#\/schema\/logo\/image\/","url":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2020\/11\/verlag-barbara-budrich-logo.jpg","contentUrl":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2020\/11\/verlag-barbara-budrich-logo.jpg","width":354,"height":354,"caption":"Verlag Barbara Budrich GmbH"},"image":{"@id":"https:\/\/shop.budrich.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product\/44903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/comments?post=44903"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/media\/47217"}],"wp:attachment":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/media?parent=44903"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product_brand?post=44903"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product_cat?post=44903"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product_tag?post=44903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}