{"id":70425,"date":"2019-06-24T09:05:00","date_gmt":"2019-06-24T08:05:13","guid":{"rendered":"https:\/\/shop.budrich-academic.de\/?post_type=product&#038;p=70425"},"modified":"2026-01-02T11:06:33","modified_gmt":"2026-01-02T10:06:33","slug":"orientierungshilfe-fachkraft-zur-arbeits-und-berufsfoerderung","status":"publish","type":"product","link":"https:\/\/shop.budrich.de\/en\/produkt\/orientierungshilfe-fachkraft-zur-arbeits-und-berufsfoerderung\/","title":{"rendered":"Orientierungshilfe Fachkraft zur Arbeits- und Berufsf\u00f6rderung"},"content":{"rendered":"<p><strong>Open Access:<\/strong> <em>Der Titel\u00a0<a class=\"wpel-icon-right\" href=\"https:\/\/www.bibb.de\/veroeffentlichungen\/de\/publication\/show\/10161\" target=\"_blank\" rel=\"noopener noreferrer nofollow external\" data-wpel-link=\"external\">Orientierungshilfe Fachkraft zur Arbeits- und Berufsf\u00f6rderung <\/a><\/em><a class=\"wpel-icon-right\" href=\"https:\/\/www.bibb.de\/veroeffentlichungen\/de\/publication\/show\/10161\" target=\"_blank\" rel=\"nofollow external noopener noreferrer\" data-wpel-link=\"external\">ist kostenlos im <strong>Open Access<\/strong> (PDF)<\/a> <em>herunterladbar oder kostenpflichtig als Print-Ausgabe erh\u00e4ltlich. <\/em><em><span lang=\"EN-US\">Dieser Beitrag ist beim Bundesinstitut f\u00fcr Berufsbildung erschienen und steht unter der Creative Commons Lizenz: <\/span><a class=\"wpel-icon-right\" href=\"https:\/\/creativecommons.org\/licenses\/by-nc-nd\/4.0\/deed.de\" target=\"_blank\" rel=\"nofollow external noopener noreferrer\" data-wpel-link=\"external\">https:\/\/creativecommons.org\/licenses\/by-nc-nd\/4.0\/deed.de<\/a><\/em><\/p>\n<p><strong>Die neue Fortbildungspr\u00fcfungsverordnung \u201eGepr\u00fcfte Fachkraft zur Arbeits- und Berufsf\u00f6rderung\u201c ist ein berufsbildungspolitisches Angebot und Ordnungsmittel, das f\u00fcr vielf\u00e4ltige Aufgaben und Einsatzfelder in der Beruflichen Bildung behinderter Menschen und deren Teilhabe am Arbeitsleben qualifiziert. Das attraktive, anspruchsvolle Qualifikationsprofil ist kompetenzorientiert und personenzentriert.<\/strong><\/p>\n<p>Die Orientierungshilfe gibt Weiterbildungsanbietern, zust\u00e4ndigen pr\u00fcfenden Stellen, Pr\u00fcfungsaussch\u00fcssen sowie an der Pr\u00fcfung Interessierten kompakte und detaillierte Informationen und Anregungen. Diese Informationen und Anregungen sollen die vielf\u00e4ltigen Fragen beantworten, die sich bei der Umsetzung der Fortbildungspr\u00fcfungsverordnung in der Praxis stellen. Zugleich will dieses Nachschlagwerk dazu beitragen, die Teilhabe behinderter Menschen durch Qualifizierung und Professionalisierung des Fachpersonals zu f\u00f6rdern.<\/p>","protected":false},"excerpt":{"rendered":"<p>Open Access: Der Titel\u00a0Orientierungshilfe Fachkraft zur Arbeits- und Berufsf\u00f6rderung ist kostenlos im Open Access (PDF) herunterladbar oder kostenpflichtig als Print-Ausgabe erh\u00e4ltlich. Dieser Beitrag ist beim Bundesinstitut f\u00fcr Berufsbildung erschienen und steht unter der Creative Commons Lizenz: https:\/\/creativecommons.org\/licenses\/by-nc-nd\/4.0\/deed.de Die neue Fortbildungspr\u00fcfungsverordnung \u201eGepr\u00fcfte Fachkraft zur Arbeits- und Berufsf\u00f6rderung\u201c ist ein berufsbildungspolitisches Angebot und Ordnungsmittel, das f\u00fcr vielf\u00e4ltige [&hellip;]<\/p>\n","protected":false},"featured_media":80357,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[7609],"product_tag":[31938,27976,27977,7776,31934,9786,31935,13810,31936,31937,25874],"class_list":{"0":"post-70425","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_author-kirsten-vollmer","7":"product_author-gisela-mettin","8":"product_author-claudia-frohnenberg","9":"product_cat-erziehung","10":"product_tag-qualifizierungslehrgaenge","11":"product_tag-deutscher-qualifikationsrahmen","12":"product_tag-anerkennung-beruflicher-qualifikationen","13":"product_tag-inklusion","14":"product_tag-berufliche-foerderung","15":"product_tag-berufsbildung","16":"product_tag-kompetenzorientierte-bildung","17":"product_tag-teilhabe","18":"product_tag-personenzentrierte-berufsbildung","19":"product_tag-berufsbildungsgesetz","20":"product_tag-pruefungen","21":"pa_reihe-berufsbildung-in-der-praxis","22":"pa_verlag-verlag-barbara-budrich","23":"wpbf-post","26":"instock","27":"taxable","28":"shipping-taxable","29":"purchasable","30":"product-type-variable","31":"has-default-attributes"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Orientierungshilfe Fachkraft zur Arbeits- und Berufsf\u00f6rderung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/shop.budrich.de\/en\/product-2\/orientierungshilfe-fachkraft-zur-arbeits-und-berufsfoerderung\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Orientierungshilfe Fachkraft zur Arbeits- und Berufsf\u00f6rderung\" \/>\n<meta property=\"og:description\" content=\"Open Access: Der Titel\u00a0Orientierungshilfe Fachkraft zur Arbeits- und Berufsf\u00f6rderung ist kostenlos im Open Access (PDF) herunterladbar oder kostenpflichtig als Print-Ausgabe erh\u00e4ltlich. Dieser Beitrag ist beim Bundesinstitut f\u00fcr Berufsbildung erschienen und steht unter der Creative Commons Lizenz: https:\/\/creativecommons.org\/licenses\/by-nc-nd\/4.0\/deed.de Die neue Fortbildungspr\u00fcfungsverordnung \u201eGepr\u00fcfte Fachkraft zur Arbeits- und Berufsf\u00f6rderung\u201c ist ein berufsbildungspolitisches Angebot und Ordnungsmittel, das f\u00fcr vielf\u00e4ltige [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/shop.budrich.de\/en\/product-2\/orientierungshilfe-fachkraft-zur-arbeits-und-berufsfoerderung\/\" \/>\n<meta property=\"og:site_name\" content=\"Verlag Barbara Budrich\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-02T10:06:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/shop.budrich.de\/wp-content\/uploads\/2021\/02\/9783847429944-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1448\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/orientierungshilfe-fachkraft-zur-arbeits-und-berufsfoerderung\\\/\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/orientierungshilfe-fachkraft-zur-arbeits-und-berufsfoerderung\\\/\",\"name\":\"Orientierungshilfe Fachkraft zur Arbeits- und Berufsf\u00f6rderung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/orientierungshilfe-fachkraft-zur-arbeits-und-berufsfoerderung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/orientierungshilfe-fachkraft-zur-arbeits-und-berufsfoerderung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/9783847429944-scaled.jpg\",\"datePublished\":\"2019-06-24T08:05:13+00:00\",\"dateModified\":\"2026-01-02T10:06:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/orientierungshilfe-fachkraft-zur-arbeits-und-berufsfoerderung\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/orientierungshilfe-fachkraft-zur-arbeits-und-berufsfoerderung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/orientierungshilfe-fachkraft-zur-arbeits-und-berufsfoerderung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/9783847429944-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/9783847429944-scaled.jpg\",\"width\":1448,\"height\":2048,\"caption\":\"Orientierungshilfe Fachkraft zur Arbeits- und Berufsf\u00f6rderung\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/produkt\\\/orientierungshilfe-fachkraft-zur-arbeits-und-berufsfoerderung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/shop.budrich.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Programm\",\"item\":\"https:\\\/\\\/shop.budrich.de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Orientierungshilfe Fachkraft zur Arbeits- und Berufsf\u00f6rderung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#website\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/\",\"name\":\"Verlag Barbara Budrich\",\"description\":\"Qualitativ hochwertige Publikationen f\u00fcr die Sozial- und Erziehungswissenschaften\",\"publisher\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/shop.budrich.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#organization\",\"name\":\"Verlag Barbara Budrich GmbH\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/verlag-barbara-budrich-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/shop.budrich.de\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/verlag-barbara-budrich-logo.jpg\",\"width\":354,\"height\":354,\"caption\":\"Verlag Barbara Budrich GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/shop.budrich.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Orientierungshilfe Fachkraft zur Arbeits- und Berufsf\u00f6rderung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/shop.budrich.de\/en\/product-2\/orientierungshilfe-fachkraft-zur-arbeits-und-berufsfoerderung\/","og_locale":"en_US","og_type":"article","og_title":"Orientierungshilfe Fachkraft zur Arbeits- und Berufsf\u00f6rderung","og_description":"Open Access: Der Titel\u00a0Orientierungshilfe Fachkraft zur Arbeits- und Berufsf\u00f6rderung ist kostenlos im Open Access (PDF) herunterladbar oder kostenpflichtig als Print-Ausgabe erh\u00e4ltlich. Dieser Beitrag ist beim Bundesinstitut f\u00fcr Berufsbildung erschienen und steht unter der Creative Commons Lizenz: https:\/\/creativecommons.org\/licenses\/by-nc-nd\/4.0\/deed.de Die neue Fortbildungspr\u00fcfungsverordnung \u201eGepr\u00fcfte Fachkraft zur Arbeits- und Berufsf\u00f6rderung\u201c ist ein berufsbildungspolitisches Angebot und Ordnungsmittel, das f\u00fcr vielf\u00e4ltige [&hellip;]","og_url":"https:\/\/shop.budrich.de\/en\/product-2\/orientierungshilfe-fachkraft-zur-arbeits-und-berufsfoerderung\/","og_site_name":"Verlag Barbara Budrich","article_modified_time":"2026-01-02T10:06:33+00:00","og_image":[{"width":1448,"height":2048,"url":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2021\/02\/9783847429944-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/shop.budrich.de\/produkt\/orientierungshilfe-fachkraft-zur-arbeits-und-berufsfoerderung\/","url":"https:\/\/shop.budrich.de\/produkt\/orientierungshilfe-fachkraft-zur-arbeits-und-berufsfoerderung\/","name":"Orientierungshilfe Fachkraft zur Arbeits- und Berufsf\u00f6rderung","isPartOf":{"@id":"https:\/\/shop.budrich.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/shop.budrich.de\/produkt\/orientierungshilfe-fachkraft-zur-arbeits-und-berufsfoerderung\/#primaryimage"},"image":{"@id":"https:\/\/shop.budrich.de\/produkt\/orientierungshilfe-fachkraft-zur-arbeits-und-berufsfoerderung\/#primaryimage"},"thumbnailUrl":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2021\/02\/9783847429944-scaled.jpg","datePublished":"2019-06-24T08:05:13+00:00","dateModified":"2026-01-02T10:06:33+00:00","breadcrumb":{"@id":"https:\/\/shop.budrich.de\/produkt\/orientierungshilfe-fachkraft-zur-arbeits-und-berufsfoerderung\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/shop.budrich.de\/produkt\/orientierungshilfe-fachkraft-zur-arbeits-und-berufsfoerderung\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/shop.budrich.de\/produkt\/orientierungshilfe-fachkraft-zur-arbeits-und-berufsfoerderung\/#primaryimage","url":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2021\/02\/9783847429944-scaled.jpg","contentUrl":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2021\/02\/9783847429944-scaled.jpg","width":1448,"height":2048,"caption":"Orientierungshilfe Fachkraft zur Arbeits- und Berufsf\u00f6rderung"},{"@type":"BreadcrumbList","@id":"https:\/\/shop.budrich.de\/produkt\/orientierungshilfe-fachkraft-zur-arbeits-und-berufsfoerderung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/shop.budrich.de\/"},{"@type":"ListItem","position":2,"name":"Programm","item":"https:\/\/shop.budrich.de\/shop\/"},{"@type":"ListItem","position":3,"name":"Orientierungshilfe Fachkraft zur Arbeits- und Berufsf\u00f6rderung"}]},{"@type":"WebSite","@id":"https:\/\/shop.budrich.de\/#website","url":"https:\/\/shop.budrich.de\/","name":"Verlag Barbara Budrich","description":"Qualitativ hochwertige Publikationen f\u00fcr die Sozial- und Erziehungswissenschaften","publisher":{"@id":"https:\/\/shop.budrich.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/shop.budrich.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/shop.budrich.de\/#organization","name":"Verlag Barbara Budrich GmbH","url":"https:\/\/shop.budrich.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/shop.budrich.de\/#\/schema\/logo\/image\/","url":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2020\/11\/verlag-barbara-budrich-logo.jpg","contentUrl":"https:\/\/shop.budrich.de\/wp-content\/uploads\/2020\/11\/verlag-barbara-budrich-logo.jpg","width":354,"height":354,"caption":"Verlag Barbara Budrich GmbH"},"image":{"@id":"https:\/\/shop.budrich.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product\/70425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/comments?post=70425"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/media\/80357"}],"wp:attachment":[{"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/media?parent=70425"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product_brand?post=70425"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product_cat?post=70425"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.budrich.de\/en\/wp-json\/wp\/v2\/product_tag?post=70425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}